{"id":1390,"date":"2016-12-09T19:19:00","date_gmt":"2016-12-09T18:19:00","guid":{"rendered":"http:\/\/www.lacostituzione.info\/?p=1390"},"modified":"2018-01-03T11:14:07","modified_gmt":"2018-01-03T10:14:07","slug":"legge-elettorale-perche-il-parlamento-dovrebbe-decidere-prima-della-corte","status":"publish","type":"post","link":"https:\/\/www.lacostituzione.info\/index.php\/2016\/12\/09\/legge-elettorale-perche-il-parlamento-dovrebbe-decidere-prima-della-corte\/","title":{"rendered":"Legge elettorale: perch\u00e9 il Parlamento <br> dovrebbe decidere prima della Corte"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1395\" data-permalink=\"https:\/\/www.lacostituzione.info\/index.php\/2016\/12\/09\/legge-elettorale-perche-il-parlamento-dovrebbe-decidere-prima-della-corte\/image-56\/#main\" data-orig-file=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2016\/12\/image-2.jpeg\" data-orig-size=\"1025,593\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"image\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2016\/12\/image-2-300x174.jpeg\" data-large-file=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2016\/12\/image-2-1024x592.jpeg\" class=\"alignleft wp-image-1395 size-thumbnail\" src=\"http:\/\/www.lacostituzione.info\/wp-content\/uploads\/2016\/12\/image-2-150x150.jpeg\" alt=\"image\" width=\"150\" height=\"150\" \/>di <b>Alessandro Morelli<\/b><\/p>\n<p>Dopo il 4 dicembre 2016, la prossima data da segnare su un calendario politico sempre pi\u00f9 ansiogeno \u00e8 il 24 gennaio 2017, giorno in cui, a Palazzo della Consulta, si svolger\u00e0 l\u2019udienza del giudizio relativo all\u2019Italicum.<!--more-->Tra politici e commentatori si \u00e8 rapidamente diffusa l\u2019idea che il Parlamento dovrebbe attendere la pronuncia della Corte costituzionale e che non potrebbe mettere mano subito alle leggi elettorali di Camera e Senato, per renderle anche solo coerenti. Qualcuno ha persino sostenuto che un intervento legislativo si configurerebbe ora come una \u201cscortesia istituzionale\u201d nei confronti dei giudici della Consulta, come se non fosse una prerogativa delle Camere quella di decidere in materia elettorale (ovviamente nel rispetto della legalit\u00e0 costituzionale). <!--more--><\/p>\n<p>Si trascura che la Corte \u00e8 un organo di garanzia, chiamato a pronunciarsi nelle forme e con i metodi della giurisdizione. \u00c8 un giudice, anche se politico \u00e8 l\u2019oggetto del suo giudizio: la legge. Certo, questo apparente ossimoro, nel quale pure trova espressione uno dei connotati fondamentali della forma di Stato vigente, pu\u00f2 generare confusione in chi non ha dimestichezza con i principi del costituzionalismo e con le esigenze di limitazione giuridica del potere politico. E cos\u00ec molti vedono dietro tutte le decisioni del Giudice delle leggi, comprese quelle relative alla calendarizzazione delle sue udienze, scelte di opportunit\u00e0 politica, laddove spesso stanno solo ragioni di ordine tecnico e regole processuali.<\/p>\n<p>Ora, la decisione che la Corte emetter\u00e0 sull\u2019Italicum rischia di generare un ulteriore equivoco. Il giudizio potrebbe concludersi con una pronuncia d\u2019inammissibilit\u00e0, con una di rigetto o con una di accoglimento. Quando il Giudice delle leggi accoglie la questione, dichiara l\u2019illegittimit\u00e0 della legge impugnata e la espunge dall\u2019ordinamento. Se, invece, pronuncia l\u2019inammissibilit\u00e0 della questione, la Corte non entra nel merito, rilevando la mancanza di condizioni necessarie all\u2019instaurazione del giudizio. Se, infine, emette una decisione di rigetto, dichiara l\u2019infondatezza della questione, affermando l\u2019insussistenza del vizio di legittimit\u00e0, ma solo nei limiti in cui tale vizio \u00e8 stato denunciato nell\u2019atto introduttivo del giudizio. Quando la Consulta pronuncia una sentenza di rigetto, non d\u00e0 alcuna patente di costituzionalit\u00e0 alla legge impugnata. La Corte, in sostanza, pu\u00f2 dichiarare che una legge \u00e8 illegittima, ma non che essa \u00e8 totalmente e definitivamente legittima. E, infatti, chiunque, nelle forme appropriate, pu\u00f2 impugnare nuovamente una legge uscita indenne da un giudizio di costituzionalit\u00e0. E una legge fatta salva dalla Corte non diventa intoccabile per lo stesso Parlamento, che pu\u00f2 modificarne come meglio crede il contenuto e persino abrogarla.<\/p>\n<p>Si tratta di sottigliezze da giuristi? Pu\u00f2 darsi. Il rischio di sottovalutare tali \u201csottigliezze\u201d \u00e8, per\u00f2, quello di alimentare una nuova mitizzazione della pronuncia della Corte sull\u2019Italicum. Se le questioni di costituzionalit\u00e0 sollevate saranno accolte, non dovr\u00e0 leggersi la decisione come una definitiva bocciatura del maggioritario (a favore del proporzionale), cos\u00ec come il rigetto delle medesime questioni non comporter\u00e0 alcuna \u201ccostituzionalizzazione\u201d della formula maggioritaria (o la necessit\u00e0 di estendere l\u2019Italicum anche al Senato). Che tali fraintendimenti si abbiano, tuttavia, \u00e8 molto probabile.<\/p>\n<p>Per questo, sarebbe bene che le Camere anticipassero il giudizio della Corte, intervenendo anche sugli aspetti pi\u00f9 problematici della legge elettorale della Camera. Non si tratterebbe di uno sgarbo istituzionale, ma di un normale esercizio delle attribuzioni parlamentari, che avrebbe anche il merito di restituire alle Camere (e alle forze politiche in esse presenti) la responsabilit\u00e0 di una scelta tutta politica, dalla quale dipender\u00e0, in gran parte, il futuro delle istituzioni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>di Alessandro Morelli Dopo il 4 dicembre 2016, la prossima data da segnare su un calendario politico sempre pi\u00f9 ansiogeno \u00e8 il 24 gennaio 2017, giorno in cui, a Palazzo della Consulta, si svolger\u00e0 l\u2019udienza del giudizio relativo all\u2019Italicum.<\/p>\n<div class='heateorSssClear'><\/div><div  class='heateor_sss_sharing_container heateor_sss_horizontal_sharing' data-heateor-sss-href='https:\/\/www.lacostituzione.info\/index.php\/2016\/12\/09\/legge-elettorale-perche-il-parlamento-dovrebbe-decidere-prima-della-corte\/'><div class='heateor_sss_sharing_title' style=\"font-weight:bold\" >Condividi!<\/div><div class=\"heateor_sss_sharing_ul\"><a aria-label=\"Facebook\" class=\"heateor_sss_facebook\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2016%2F12%2F09%2Flegge-elettorale-perche-il-parlamento-dovrebbe-decidere-prima-della-corte%2F\" title=\"Facebook\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#0765FE;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path fill=\"#fff\" d=\"M28 16c0-6.627-5.373-12-12-12S4 9.373 4 16c0 5.628 3.875 10.35 9.101 11.647v-7.98h-2.474V16H13.1v-1.58c0-4.085 1.849-5.978 5.859-5.978.76 0 2.072.15 2.608.298v3.325c-.283-.03-.775-.045-1.386-.045-1.967 0-2.728.745-2.728 2.683V16h3.92l-.673 3.667h-3.247v8.245C23.395 27.195 28 22.135 28 16Z\"><\/path><\/svg><\/span><\/a><a aria-label=\"Twitter\" class=\"heateor_sss_button_twitter\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Legge%20elettorale%3A%20perch%C3%A9%20il%20Parlamento%20%3Cbr%3E%20dovrebbe%20decidere%20prima%20della%20Corte&url=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2016%2F12%2F09%2Flegge-elettorale-perche-il-parlamento-dovrebbe-decidere-prima-della-corte%2F\" title=\"Twitter\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_twitter\" style=\"background-color:#55acee;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 39 39\"><path d=\"M28 8.557a9.913 9.913 0 0 1-2.828.775 4.93 4.93 0 0 0 2.166-2.725 9.738 9.738 0 0 1-3.13 1.194 4.92 4.92 0 0 0-3.593-1.55 4.924 4.924 0 0 0-4.794 6.049c-4.09-.21-7.72-2.17-10.15-5.15a4.942 4.942 0 0 0-.665 2.477c0 1.71.87 3.214 2.19 4.1a4.968 4.968 0 0 1-2.23-.616v.06c0 2.39 1.7 4.38 3.952 4.83-.414.115-.85.174-1.297.174-.318 0-.626-.03-.928-.086a4.935 4.935 0 0 0 4.6 3.42 9.893 9.893 0 0 1-6.114 2.107c-.398 0-.79-.023-1.175-.068a13.953 13.953 0 0 0 7.55 2.213c9.056 0 14.01-7.507 14.01-14.013 0-.213-.005-.426-.015-.637.96-.695 1.795-1.56 2.455-2.55z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a aria-label=\"Reddit\" class=\"heateor_sss_button_reddit\" href=\"https:\/\/reddit.com\/submit?url=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2016%2F12%2F09%2Flegge-elettorale-perche-il-parlamento-dovrebbe-decidere-prima-della-corte%2F&title=Legge%20elettorale%3A%20perch%C3%A9%20il%20Parlamento%20%3Cbr%3E%20dovrebbe%20decidere%20prima%20della%20Corte\" title=\"Reddit\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_reddit\" style=\"background-color:#ff5700;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-3.5 -3.5 39 39\"><path d=\"M28.543 15.774a2.953 2.953 0 0 0-2.951-2.949 2.882 2.882 0 0 0-1.9.713 14.075 14.075 0 0 0-6.85-2.044l1.38-4.349 3.768.884a2.452 2.452 0 1 0 .24-1.176l-4.274-1a.6.6 0 0 0-.709.4l-1.659 5.224a14.314 14.314 0 0 0-7.316 2.029 2.908 2.908 0 0 0-1.872-.681 2.942 2.942 0 0 0-1.618 5.4 5.109 5.109 0 0 0-.062.765c0 4.158 5.037 7.541 11.229 7.541s11.22-3.383 11.22-7.541a5.2 5.2 0 0 0-.053-.706 2.963 2.963 0 0 0 1.427-2.51zm-18.008 1.88a1.753 1.753 0 0 1 1.73-1.74 1.73 1.73 0 0 1 1.709 1.74 1.709 1.709 0 0 1-1.709 1.711 1.733 1.733 0 0 1-1.73-1.711zm9.565 4.968a5.573 5.573 0 0 1-4.081 1.272h-.032a5.576 5.576 0 0 1-4.087-1.272.6.6 0 0 1 .844-.854 4.5 4.5 0 0 0 3.238.927h.032a4.5 4.5 0 0 0 3.237-.927.6.6 0 1 1 .844.854zm-.331-3.256a1.726 1.726 0 1 1 1.709-1.712 1.717 1.717 0 0 1-1.712 1.712z\" fill=\"#fff\"\/><\/svg><\/span><\/a><a aria-label=\"Linkedin\" class=\"heateor_sss_button_linkedin\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2016%2F12%2F09%2Flegge-elettorale-perche-il-parlamento-dovrebbe-decidere-prima-della-corte%2F\" title=\"Linkedin\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_linkedin\" style=\"background-color:#0077b5;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path d=\"M6.227 12.61h4.19v13.48h-4.19V12.61zm2.095-6.7a2.43 2.43 0 0 1 0 4.86c-1.344 0-2.428-1.09-2.428-2.43s1.084-2.43 2.428-2.43m4.72 6.7h4.02v1.84h.058c.56-1.058 1.927-2.176 3.965-2.176 4.238 0 5.02 2.792 5.02 6.42v7.395h-4.183v-6.56c0-1.564-.03-3.574-2.178-3.574-2.18 0-2.514 1.7-2.514 3.46v6.668h-4.187V12.61z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a aria-label=\"Pinterest\" class=\"heateor_sss_button_pinterest\" href=\"https:\/\/www.lacostituzione.info\/index.php\/2016\/12\/09\/legge-elettorale-perche-il-parlamento-dovrebbe-decidere-prima-della-corte\/\" onclick=\"event.preventDefault();javascript:void( (function() {var e=document.createElement('script' );e.setAttribute('type','text\/javascript' );e.setAttribute('charset','UTF-8' );e.setAttribute('src','\/\/assets.pinterest.com\/js\/pinmarklet.js?r='+Math.random()*99999999);document.body.appendChild(e)})());\" title=\"Pinterest\" rel=\"noopener\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_pinterest\" style=\"background-color:#cc2329;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-2 -2 35 35\"><path fill=\"#fff\" d=\"M16.539 4.5c-6.277 0-9.442 4.5-9.442 8.253 0 2.272.86 4.293 2.705 5.046.303.125.574.005.662-.33.061-.231.205-.816.27-1.06.088-.331.053-.447-.191-.736-.532-.627-.873-1.439-.873-2.591 0-3.338 2.498-6.327 6.505-6.327 3.548 0 5.497 2.168 5.497 5.062 0 3.81-1.686 7.025-4.188 7.025-1.382 0-2.416-1.142-2.085-2.545.397-1.674 1.166-3.48 1.166-4.689 0-1.081-.581-1.983-1.782-1.983-1.413 0-2.548 1.462-2.548 3.419 0 1.247.421 2.091.421 2.091l-1.699 7.199c-.505 2.137-.076 4.755-.039 5.019.021.158.223.196.314.077.13-.17 1.813-2.247 2.384-4.324.162-.587.929-3.631.929-3.631.46.876 1.801 1.646 3.227 1.646 4.247 0 7.128-3.871 7.128-9.053.003-3.918-3.317-7.568-8.361-7.568z\"\/><\/svg><\/span><\/a><a aria-label=\"Whatsapp\" class=\"heateor_sss_whatsapp\" href=\"https:\/\/api.whatsapp.com\/send?text=Legge%20elettorale%3A%20perch%C3%A9%20il%20Parlamento%20%3Cbr%3E%20dovrebbe%20decidere%20prima%20della%20Corte%20https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2016%2F12%2F09%2Flegge-elettorale-perche-il-parlamento-dovrebbe-decidere-prima-della-corte%2F\" title=\"Whatsapp\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#55eb4c;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-6 -5 40 40\"><path class=\"heateor_sss_svg_stroke heateor_sss_no_fill\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\" d=\"M 11.579798566743314 24.396926207859085 A 10 10 0 1 0 6.808479557110079 20.73576436351046\"><\/path><path d=\"M 7 19 l -1 6 l 6 -1\" class=\"heateor_sss_no_fill heateor_sss_svg_stroke\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\"><\/path><path d=\"M 10 10 q -1 8 8 11 c 5 -1 0 -6 -1 -3 q -4 -3 -5 -5 c 4 -2 -1 -5 -1 -4\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><\/div><div class=\"heateorSssClear\"><\/div><\/div><div class='heateorSssClear'><\/div>","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"enabled":false},"version":2}},"categories":[4],"tags":[183,149,102,37,113],"class_list":["post-1390","post","type-post","status-publish","format-standard","hentry","category-attualita","tag-camere","tag-corte-costituzionale","tag-italicum","tag-legge-elettorale","tag-parlamento"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p84sDq-mq","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/posts\/1390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/comments?post=1390"}],"version-history":[{"count":0,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/posts\/1390\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/media?parent=1390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/categories?post=1390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/tags?post=1390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}