{"id":2229,"date":"2017-03-21T19:17:21","date_gmt":"2017-03-21T18:17:21","guid":{"rendered":"http:\/\/www.lacostituzione.info\/?p=2229"},"modified":"2018-01-03T10:49:26","modified_gmt":"2018-01-03T09:49:26","slug":"la-decisione-del-senato-su-minzolini-legittima-ma-talora-erroneamente-motivata","status":"publish","type":"post","link":"https:\/\/www.lacostituzione.info\/index.php\/2017\/03\/21\/la-decisione-del-senato-su-minzolini-legittima-ma-talora-erroneamente-motivata\/","title":{"rendered":"La decisione del Senato su Minzolini: <br> legittima, ma (talora) erroneamente motivata"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2231\" data-permalink=\"https:\/\/www.lacostituzione.info\/index.php\/2017\/03\/21\/la-decisione-del-senato-su-minzolini-legittima-ma-talora-erroneamente-motivata\/th-65\/#main\" data-orig-file=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2017\/03\/th-4.jpg\" data-orig-size=\"300,191\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"th\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2017\/03\/th-4-300x191.jpg\" data-large-file=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2017\/03\/th-4.jpg\" class=\"alignright wp-image-2231 size-thumbnail\" src=\"http:\/\/www.lacostituzione.info\/wp-content\/uploads\/2017\/03\/th-4-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>di<strong> Salvatore Curreri<\/strong><\/p>\n<p>Prima o poi sarebbe accaduto. E cos\u00ec, dopo i voti per la decadenza di Galan (alla Camera) e di Berlusconi (al Senato), \u00e8 stato il sen. Augusto Minzolini il primo parlamentare a non essere dichiarato decaduto, bench\u00e9 condannato in via definitiva a pi\u00f9 di due anni per uno dei reati (nel caso in specie quello di peculato) per cui il c.d. decreto Severino (d.lgs. 235\/2012) prevede l\u2019incandidabilit\u00e0 (art. 1), anche se sopravvenuta in corso di mandato (art. 3).<!--more--><\/p>\n<p>Era perci\u00f2 ampiamente prevedibile che tale voto scatenasse le proteste di buona parte dell\u2019opinione pubblica contro quella che \u00e8 stata ritenuta l\u2019ennesima manifestazione di protervia della casta politica. Meno prevedibile, sinceramente, che taluni senatori giustificassero il loro voto, favorevole o contrario, ricorrendo ad argomenti costituzionalmente opinabili.<\/p>\n<p>\u00c8 il caso, quindi, di fare un po\u2019 di chiarezza, anche per il futuro.<\/p>\n<p>Innanzi tutto, in caso di sopraggiunta causa d\u2019incandidabilit\u00e0 di un parlamentare, la Camera d\u2019appartenenza non \u00e8 chiamata a \u201cprendere atto\u201d o a \u201cratificare\u201d la sentenza di condanna, dichiarandone l\u2019automatica decadenza dal mandato, ma, come recita l\u2019art. 3.1 del citato decreto Severino, deve deliberare \u201cai sensi dell\u2019articolo 66 della Costituzione\u201d. Articolo secondo cui \u201cciascuna Camera <em>giudica<\/em> dei titoli di ammissione dei suoi componenti e delle cause sopraggiunte di ineleggibilit\u00e0 e di incompatibilit\u00e0\u201d (c.d. autodichia; corsivo mio). Pertanto, al contrario di altri ordinamenti costituzionali, nel nostro sono esclusivamente le Camere che devono non \u201caccertare\u201d o \u201cdichiarare\u201d ma \u201cgiudicare\u201d dei titoli di ammissione e, quindi, della permanenza in carica dei propri componenti, anche a seguito di \u201ccause sopraggiunte di ineleggibilit\u00e0\u201d (e la incandidabilit\u00e0 \u00e8 una particolare forma d\u2019ineleggibilit\u00e0: v. Corte cost. 132\/2001, 2\u00b0 cons. dir.).<\/p>\n<p>Ai sensi dell\u2019art. 66 Cost., dunque, sono solo le camere a poter decidere sovranamente della propria composizione: n\u00e9 la magistratura, n\u00e9 lo stesso eletto (le cui dimissioni, per questo motivo, sono soggette ad approvazione). Del resto, fu proprio per evitare problemi di costituzionalit\u00e0 che l\u2019attuale formulazione del sopra citato art. 3.1 fu preferita a quella iniziale che in tali casi invece prevedeva \u201cla decadenza <em>di diritto<\/em> dalla carica, (\u2026) <em>dichiarata<\/em> dalla Camera di appartenenza\u201d (corsivi miei; cfr. <a href=\"http:\/\/www.huffingtonpost.it\/2013\/08\/19\/incandidabilita-berlusconi-legge-severino-governo-monti_n_3779468.html?utm_hp_ref=italy\">http:\/\/www.huffingtonpost.it\/2013\/08\/19\/incandidabilita-berlusconi-legge-severino-governo-monti_n_3779468.html?utm_hp_ref=italy<\/a>). \u00c8 errato, quindi, a mio parere, ritenere che, in tali casi, il voto per la decadenza sia un atto dovuto e non discrezionale. Di esso i parlamentari, in piena libert\u00e0 di mandato, si assumono la responsabilit\u00e0 politica dinanzi ai loro elettori e, pi\u00f9 in generale, all\u2019opinione pubblica.<\/p>\n<p>Ma parimenti errato \u00e8, a mio parere, giustificare il voto contrario alla decadenza per il <em>fumus persecutionis <\/em>di cui il sen. Minzolini sarebbe stato vittima perch\u00e9, dopo essere stato non condannato in sede civile ed assolto in primo grado in sede penale, egli \u00e8 stato, invece, dichiarato colpevole \u00a0dalla Corte di appello senza nuova audizione dei testimoni e ad una pena appositamente aumentata a due anni e mezzo di reclusione cos\u00ec da far scattare l\u2019applicazione del decreto Severino.<\/p>\n<p>Innanzi tutto, chi ha avuto un giudizio favorevole in sede civile non per questo va scagionato in sede penale, trattandosi ovviamente di processi basati su presupposti diversi. In secondo luogo, \u00e8 ben strano che il sen. Minzolini non abbia mai eccepito nel processo, come pur avrebbe potuto tramite istanza di ricusazione, la mancata imparzialit\u00e0 e terziet\u00e0 del collegio giudicante (per la presenza tra i tre giudici di un ex parlamentare e sottosegretario nel governo Prodi, di opposto orientamento politico). Ma soprattutto \u00e8 la natura definitiva della sentenza penale di condanna, dopo due giudizi di merito ed uno di legittimit\u00e0, che esclude in radice l\u2019ipotetico intento persecutorio. \u00c8 questo, infatti, il motivo per cui l\u2019art. 68.2 Cost. esclude l\u2019autorizzazione della camera di appartenenza quando si debba privare un parlamentare della libert\u00e0 personale \u201cin esecuzione di una sentenza irrevocabile di condanna\u201d.<\/p>\n<p>Certo si possono separare i due piani, sostenendo che i magistrati possano, in diabolico concerto, perseguitare (e non perseguire) un parlamentare fino al punto di condannarlo in via definitiva e mandarlo in carcere (non nel caso per\u00f2 del sen. Minzolini, condannato con la condizionale), senza per\u00f2 poterlo privare del suo mandato. Epper\u00f2, spero si vorr\u00e0 convenire sulla gravit\u00e0 della situazione, un po\u2019 paradossale, in cui si verrebbe a trovare il parlamentare perseguitato che, pur rimanendo tale in carcere, non potrebbe comunque esercitare il suo mandato, almeno per quanto riguarda quelle funzioni che richiedono la sua presenza fisica a Palazzo Madama o a Montecitorio.<\/p>\n<p>Il fatto \u00e8, invece, che la definitivit\u00e0 della sentenza penale di condanna esclude <em>in re ipsa <\/em>ogni ipotesi persecutoria per cui, cos\u00ec come consente che il parlamentare venga privato della sua libert\u00e0 personale senza necessit\u00e0 dell\u2019autorizzazione a procedere della camera di appartenenza, allo stesso modo dovrebbe consentirne, almeno sotto questo profilo, la decadenza dal mandato. Diversamente, facendo prevalere l\u2019art. 66 sull\u2019art. 68.2 Cost., si finisce di fatto per resuscitare la vecchia autorizzazione a procedere antecedente alla riforma del 1993, cio\u00e8 richiesta anche quando si trattava di dare esecuzione a sentenze penali definitive di condanna.<\/p>\n<p>Parimenti opinabile pare la motivazione di chi ha votato contro la decadenza del sen. Minzolini contestando la violazione del principio d\u2019irretroattivit\u00e0 delle norme penali, giacch\u00e9 altrimenti si sarebbe applicato un istituto di natura sanzionatoria introdotto dal 2013 a fatti commessi antecedentemente. La Corte costituzionale, infatti, ha definitivamente chiarito che le misure dell\u2019incandidabilit\u00e0, della decadenza e della sospensione degli amministratori pubblici \u201cnon costituiscono sanzioni o effetti penali della condanna, ma conseguenze del venir meno di un requisito soggettivo per l\u2019accesso alle cariche considerato o per il loro mantenimento\u201d(sentenza n. 236\/2015, 4.1 cons. dir.). In virt\u00f9 di tale giurisprudenza, dunque, la decadenza dal mandato parlamentare non costituisce una sanzione o un effetto penale della condanna, ma la conseguenza del venir meno d\u2019un requisito soggettivo per l&#8217;accesso alle cariche elettive o per il loro mantenimento, nell&#8217;ambito di quanto dettato dall&#8217;articolo 51.1 Cost. (che attribuisce al legislatore il potere di stabilire i requisiti di eleggibilit\u00e0) e non in quello dell&#8217;articolo 25.2 (che sancisce il principio di irretroattivit\u00e0 della legge penale).<\/p>\n<p>Un\u2019ultima considerazione. La Giunta delle elezioni del Senato, nel suo parere reso all\u2019Aula (favorevole alla decadenza), ha ribadito la sua natura di organo politico, e non giurisdizionale, inidoneo quindi a sollevare in materia questioni di legittimit\u00e0 costituzionale o rinvii pregiudiziali interpretativi alle Corte europee di Strasburgo e Lussemburgo (causa questa non ultima dell\u2019ammissibilit\u00e0 da parte della Corte costituzionale delle azioni di accertamento in materia di legge elettorale). Preso atto di tale orientamento, deve essere dunque il legislatore &#8211; e non altri \u2013 ad intervenire sulla disciplina della incandidabilit\u00e0 per sciogliere i numerosi dubbi interpretativi insorti. Non certo per abbassare il livello di guardia verso simili comportamenti delittuosi che, quando commessi da parlamentari, suscitano giusto sconcerto nell\u2019opinione pubblica.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>di Salvatore Curreri Prima o poi sarebbe accaduto. E cos\u00ec, dopo i voti per la decadenza di Galan (alla Camera) e di Berlusconi (al Senato), \u00e8 stato il sen. Augusto Minzolini il primo parlamentare a non essere dichiarato decaduto, bench\u00e9 condannato in via definitiva a pi\u00f9 di due anni per uno dei reati (nel caso &#8230; <a title=\"La decisione del Senato su Minzolini: &lt;br&gt; legittima, ma (talora) erroneamente motivata\" class=\"read-more\" href=\"https:\/\/www.lacostituzione.info\/index.php\/2017\/03\/21\/la-decisione-del-senato-su-minzolini-legittima-ma-talora-erroneamente-motivata\/\">Leggi tutto<\/a><\/p>\n<div class='heateorSssClear'><\/div><div  class='heateor_sss_sharing_container heateor_sss_horizontal_sharing' data-heateor-sss-href='https:\/\/www.lacostituzione.info\/index.php\/2017\/03\/21\/la-decisione-del-senato-su-minzolini-legittima-ma-talora-erroneamente-motivata\/'><div class='heateor_sss_sharing_title' style=\"font-weight:bold\" >Condividi!<\/div><div class=\"heateor_sss_sharing_ul\"><a aria-label=\"Facebook\" class=\"heateor_sss_facebook\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2017%2F03%2F21%2Fla-decisione-del-senato-su-minzolini-legittima-ma-talora-erroneamente-motivata%2F\" title=\"Facebook\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#0765FE;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path fill=\"#fff\" d=\"M28 16c0-6.627-5.373-12-12-12S4 9.373 4 16c0 5.628 3.875 10.35 9.101 11.647v-7.98h-2.474V16H13.1v-1.58c0-4.085 1.849-5.978 5.859-5.978.76 0 2.072.15 2.608.298v3.325c-.283-.03-.775-.045-1.386-.045-1.967 0-2.728.745-2.728 2.683V16h3.92l-.673 3.667h-3.247v8.245C23.395 27.195 28 22.135 28 16Z\"><\/path><\/svg><\/span><\/a><a aria-label=\"Twitter\" class=\"heateor_sss_button_twitter\" href=\"https:\/\/twitter.com\/intent\/tweet?text=La%20decisione%20del%20Senato%20su%20Minzolini%3A%20%3Cbr%3E%20legittima%2C%20ma%20%28talora%29%20erroneamente%20motivata&url=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2017%2F03%2F21%2Fla-decisione-del-senato-su-minzolini-legittima-ma-talora-erroneamente-motivata%2F\" title=\"Twitter\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_twitter\" style=\"background-color:#55acee;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 39 39\"><path d=\"M28 8.557a9.913 9.913 0 0 1-2.828.775 4.93 4.93 0 0 0 2.166-2.725 9.738 9.738 0 0 1-3.13 1.194 4.92 4.92 0 0 0-3.593-1.55 4.924 4.924 0 0 0-4.794 6.049c-4.09-.21-7.72-2.17-10.15-5.15a4.942 4.942 0 0 0-.665 2.477c0 1.71.87 3.214 2.19 4.1a4.968 4.968 0 0 1-2.23-.616v.06c0 2.39 1.7 4.38 3.952 4.83-.414.115-.85.174-1.297.174-.318 0-.626-.03-.928-.086a4.935 4.935 0 0 0 4.6 3.42 9.893 9.893 0 0 1-6.114 2.107c-.398 0-.79-.023-1.175-.068a13.953 13.953 0 0 0 7.55 2.213c9.056 0 14.01-7.507 14.01-14.013 0-.213-.005-.426-.015-.637.96-.695 1.795-1.56 2.455-2.55z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a aria-label=\"Reddit\" class=\"heateor_sss_button_reddit\" href=\"https:\/\/reddit.com\/submit?url=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2017%2F03%2F21%2Fla-decisione-del-senato-su-minzolini-legittima-ma-talora-erroneamente-motivata%2F&title=La%20decisione%20del%20Senato%20su%20Minzolini%3A%20%3Cbr%3E%20legittima%2C%20ma%20%28talora%29%20erroneamente%20motivata\" title=\"Reddit\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_reddit\" style=\"background-color:#ff5700;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-3.5 -3.5 39 39\"><path d=\"M28.543 15.774a2.953 2.953 0 0 0-2.951-2.949 2.882 2.882 0 0 0-1.9.713 14.075 14.075 0 0 0-6.85-2.044l1.38-4.349 3.768.884a2.452 2.452 0 1 0 .24-1.176l-4.274-1a.6.6 0 0 0-.709.4l-1.659 5.224a14.314 14.314 0 0 0-7.316 2.029 2.908 2.908 0 0 0-1.872-.681 2.942 2.942 0 0 0-1.618 5.4 5.109 5.109 0 0 0-.062.765c0 4.158 5.037 7.541 11.229 7.541s11.22-3.383 11.22-7.541a5.2 5.2 0 0 0-.053-.706 2.963 2.963 0 0 0 1.427-2.51zm-18.008 1.88a1.753 1.753 0 0 1 1.73-1.74 1.73 1.73 0 0 1 1.709 1.74 1.709 1.709 0 0 1-1.709 1.711 1.733 1.733 0 0 1-1.73-1.711zm9.565 4.968a5.573 5.573 0 0 1-4.081 1.272h-.032a5.576 5.576 0 0 1-4.087-1.272.6.6 0 0 1 .844-.854 4.5 4.5 0 0 0 3.238.927h.032a4.5 4.5 0 0 0 3.237-.927.6.6 0 1 1 .844.854zm-.331-3.256a1.726 1.726 0 1 1 1.709-1.712 1.717 1.717 0 0 1-1.712 1.712z\" fill=\"#fff\"\/><\/svg><\/span><\/a><a aria-label=\"Linkedin\" class=\"heateor_sss_button_linkedin\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2017%2F03%2F21%2Fla-decisione-del-senato-su-minzolini-legittima-ma-talora-erroneamente-motivata%2F\" title=\"Linkedin\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_linkedin\" style=\"background-color:#0077b5;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path d=\"M6.227 12.61h4.19v13.48h-4.19V12.61zm2.095-6.7a2.43 2.43 0 0 1 0 4.86c-1.344 0-2.428-1.09-2.428-2.43s1.084-2.43 2.428-2.43m4.72 6.7h4.02v1.84h.058c.56-1.058 1.927-2.176 3.965-2.176 4.238 0 5.02 2.792 5.02 6.42v7.395h-4.183v-6.56c0-1.564-.03-3.574-2.178-3.574-2.18 0-2.514 1.7-2.514 3.46v6.668h-4.187V12.61z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a aria-label=\"Pinterest\" class=\"heateor_sss_button_pinterest\" href=\"https:\/\/www.lacostituzione.info\/index.php\/2017\/03\/21\/la-decisione-del-senato-su-minzolini-legittima-ma-talora-erroneamente-motivata\/\" onclick=\"event.preventDefault();javascript:void( (function() {var e=document.createElement('script' );e.setAttribute('type','text\/javascript' );e.setAttribute('charset','UTF-8' );e.setAttribute('src','\/\/assets.pinterest.com\/js\/pinmarklet.js?r='+Math.random()*99999999);document.body.appendChild(e)})());\" title=\"Pinterest\" rel=\"noopener\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_pinterest\" style=\"background-color:#cc2329;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-2 -2 35 35\"><path fill=\"#fff\" d=\"M16.539 4.5c-6.277 0-9.442 4.5-9.442 8.253 0 2.272.86 4.293 2.705 5.046.303.125.574.005.662-.33.061-.231.205-.816.27-1.06.088-.331.053-.447-.191-.736-.532-.627-.873-1.439-.873-2.591 0-3.338 2.498-6.327 6.505-6.327 3.548 0 5.497 2.168 5.497 5.062 0 3.81-1.686 7.025-4.188 7.025-1.382 0-2.416-1.142-2.085-2.545.397-1.674 1.166-3.48 1.166-4.689 0-1.081-.581-1.983-1.782-1.983-1.413 0-2.548 1.462-2.548 3.419 0 1.247.421 2.091.421 2.091l-1.699 7.199c-.505 2.137-.076 4.755-.039 5.019.021.158.223.196.314.077.13-.17 1.813-2.247 2.384-4.324.162-.587.929-3.631.929-3.631.46.876 1.801 1.646 3.227 1.646 4.247 0 7.128-3.871 7.128-9.053.003-3.918-3.317-7.568-8.361-7.568z\"\/><\/svg><\/span><\/a><a aria-label=\"Whatsapp\" class=\"heateor_sss_whatsapp\" href=\"https:\/\/api.whatsapp.com\/send?text=La%20decisione%20del%20Senato%20su%20Minzolini%3A%20%3Cbr%3E%20legittima%2C%20ma%20%28talora%29%20erroneamente%20motivata%20https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2017%2F03%2F21%2Fla-decisione-del-senato-su-minzolini-legittima-ma-talora-erroneamente-motivata%2F\" title=\"Whatsapp\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#55eb4c;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-6 -5 40 40\"><path class=\"heateor_sss_svg_stroke heateor_sss_no_fill\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\" d=\"M 11.579798566743314 24.396926207859085 A 10 10 0 1 0 6.808479557110079 20.73576436351046\"><\/path><path d=\"M 7 19 l -1 6 l 6 -1\" class=\"heateor_sss_no_fill heateor_sss_svg_stroke\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\"><\/path><path d=\"M 10 10 q -1 8 8 11 c 5 -1 0 -6 -1 -3 q -4 -3 -5 -5 c 4 -2 -1 -5 -1 -4\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><\/div><div class=\"heateorSssClear\"><\/div><\/div><div class='heateorSssClear'><\/div>","protected":false},"author":13,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"enabled":false},"version":2}},"categories":[4],"tags":[444,442,443,441,26],"class_list":["post-2229","post","type-post","status-publish","format-standard","hentry","category-attualita","tag-decadenza-fumus-persecutionis","tag-decreto-severino","tag-incandidabilita","tag-minzolini","tag-senato"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p84sDq-zX","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/posts\/2229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/comments?post=2229"}],"version-history":[{"count":0,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/posts\/2229\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/media?parent=2229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/categories?post=2229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/tags?post=2229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}