{"id":3396,"date":"2017-12-20T15:45:34","date_gmt":"2017-12-20T14:45:34","guid":{"rendered":"http:\/\/www.lacostituzione.info\/?p=3396"},"modified":"2017-12-21T13:36:54","modified_gmt":"2017-12-21T12:36:54","slug":"quando-confliggono-diritto-interno-e-diritto-ue-una-sentenza-della-corte","status":"publish","type":"post","link":"https:\/\/www.lacostituzione.info\/index.php\/2017\/12\/20\/quando-confliggono-diritto-interno-e-diritto-ue-una-sentenza-della-corte\/","title":{"rendered":"Quando confliggono diritto interno e diritto Ue: una sentenza della Corte"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"3397\" data-permalink=\"https:\/\/www.lacostituzione.info\/index.php\/2017\/12\/20\/quando-confliggono-diritto-interno-e-diritto-ue-una-sentenza-della-corte\/th-110\/#main\" data-orig-file=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2017\/12\/th-2.jpg\" data-orig-size=\"475,265\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"th\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2017\/12\/th-2-300x167.jpg\" data-large-file=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2017\/12\/th-2.jpg\" class=\"alignleft size-medium wp-image-3397\" src=\"http:\/\/www.lacostituzione.info\/public\/wp-content\/uploads\/2017\/12\/th-2-300x167.jpg\" alt=\"\" width=\"300\" height=\"167\" srcset=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2017\/12\/th-2-300x167.jpg 300w, https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2017\/12\/th-2.jpg 475w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>di <b>Fabio Ferrari<\/b><\/p>\n<p>Una recente sentenza della Corte costituzionale, la <a href=\"https:\/\/www.cortecostituzionale.it\/actionSchedaPronuncia.do?anno=2017&amp;numero=269\">269\/2017<\/a>, introduce un\u2019importante novit\u00e0 in tema di rapporto tra diritto interno ed europeo. Al lettore non specialistico va premesso un punto. Come deve comportarsi il giudice italiano innanzi ad un\u2019incompatibilit\u00e0 tra le regole dei due ordinamenti? <!--more-->Se le norme europee, per la loro conformazione, hanno <em>efficacia diretta<\/em> \u2013 sono cio\u00e8 sufficientemente <em>precise <\/em>da risolvere direttamente il caso concreto, senza l\u2019intervento mediatore del legislatore \u2013 il giudice italiano \u00e8 tenuto a non applicare la norma nazionale con esse contrastante, garantendo cos\u00ec il primato delle prime. Se, al contrario, tale diretta efficacia manca, il giudice deve sollevare la questione di legittimit\u00e0 costituzionale alla Corte costituzionale, la quale valuter\u00e0 se annullare la norma interna.<\/p>\n<p>La sentenza in esame, con piglio ricostruttivo e ben oltre la \u201cdomanda\u201d contenuta nell\u2019ordinanza di remissione, chiarisce il modo in cui il giudice deve comportarsi innanzi ad una particolare fonte europea: la Carta di Nizza. Si tratta della Carta dei diritti fondamentali dell\u2019Unione Europea, redatta nel 2000 e successivamente incorporata nei trattati istitutivi riveduti e corretti a Lisbona (2007). La peculiarit\u00e0 di questo documento sta nel \u201ctono\u201d dei suoi precetti, essendo questi di chiara ispirazione costituzionale; proprio per questo, si caratterizzano per una costruzione delle norme a maglie sostanzialmente larghe, bisognose cio\u00e8 di una intermediazione legislativa per la loro concreta applicazione.<\/p>\n<p>Il punto sembra stare esattamente qui: non di rado \u00e8 capitato che i giudici comuni, innanzi ad un presunto contrasto tra una norma interna ed un precetto della Carta di Nizza, non applicassero autonomamente il diritto nazionale per favorire la norma europea, considerando cos\u00ec quest\u2019ultima dotata di efficacia diretta. Ci\u00f2 ha destato una qualche preoccupazione, sia per la tendenza ad un\u2019applicazione della Carta di Nizza oltre il regime di competenza dell\u2019UE, sia per la difficolt\u00e0 di concepire tali \u201campie\u201d norme ad effetto diretto. Forse \u00e8 a ci\u00f2 che la Corte ha voluto porre rimedio con la presente sentenza: in essa, dopo aver ricordato la natura sostanzialmente costituzionale della Carta di Nizza, ha precisato che un eventuale contrasto tra quest\u2019ultima e il diritto interno <em>deve <\/em>essere risolto dalla Corte costituzionale stessa, non dal giudice comune, per tramite un giudizio di costituzionalit\u00e0. Spetta dunque alla Consulta, non all\u2019attivit\u00e0 giurisdizionale diffusa sul territorio, accertare l\u2019incompatibilit\u00e0 tra le due fonti in esame, con tutte le cautele che un tale approccio sembra suggerire in tema di inveramento \u201cautomatico\u201d del contenuto della Carta di Nizza nella pratica del diritto.<\/p>\n<p>Al contempo, \u00e8 pur vero per\u00f2 che l\u2019esplicito riconoscimento di una natura sostanzialmente costituzionale alla Carta di Nizza, se preso letteralmente, potrebbe integrare nel giudizio costituzionale i principi in essa contenuti, quantomeno nell\u2019ambito del diritto di competenza UE, ispessendone solennemente il valore e il significato, ben oltre a quanto avvenuto sino ad ora per opera di qualche giudice comune. Il che, se per certi aspetti pare inevitabile, per altri impone quantomeno di interrogarsi sulla completa fungibilit\u00e0 tra le norme costituzionali e quelle della Carta di Nizza, considerata soprattutto l\u2019attenzione che le prime \u2013 a differenza delle seconde \u2013 pongono alla tutela dei diritti sociali. \u00c8 pur vero che \u00e8 la stessa Corte a precisare che la compatibilit\u00e0 tra i due documenti \u2013 Corte costituzionale e Carta di Nizza \u2013 si riscontra \u00abin larga misura\u00bb, il che significa non esaustivamente. Tuttavia, quanto realmente sia ampia quella misura merita forse di essere discusso, se non altro per il recentissimo e noto caso Taricco: nonostante i toni formali e accomodanti dell\u2019ultima pronuncia della Corte di giustizia sul punto (nella quale, proprio a stemperare la contrapposizione, si \u00e8 richiamata una presunta vicinanza in tema di diritti fondamentali tra la Carta di Nizza e la Costituzione repubblicana), il conflitto \u00e8 parso a tutti lapalissiano (<a href=\"http:\/\/www.lacostituzione.info\/index.php\/2017\/12\/06\/frodi-sulliva-e-il-caso-taricco-la-corte-di-giustizia-fa-marcia-indietro\/\">Faraguna<\/a>, <a href=\"http:\/\/www.lacostituzione.info\/index.php\/2017\/02\/18\/i-paradossi-della-vicenda-taricco\/\">Guazzarotti<\/a>).<\/p>\n<p>Nel complesso, sar\u00e0 dunque molto interessante comprendere gli sviluppi futuri di questa pronuncia.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>di Fabio Ferrari Una recente sentenza della Corte costituzionale, la 269\/2017, introduce un\u2019importante novit\u00e0 in tema di rapporto tra diritto interno ed europeo. Al lettore non specialistico va premesso un punto. Come deve comportarsi il giudice italiano innanzi ad un\u2019incompatibilit\u00e0 tra le regole dei due ordinamenti?<\/p>\n<div class='heateorSssClear'><\/div><div  class='heateor_sss_sharing_container heateor_sss_horizontal_sharing' data-heateor-sss-href='https:\/\/www.lacostituzione.info\/index.php\/2017\/12\/20\/quando-confliggono-diritto-interno-e-diritto-ue-una-sentenza-della-corte\/'><div class='heateor_sss_sharing_title' style=\"font-weight:bold\" >Condividi!<\/div><div class=\"heateor_sss_sharing_ul\"><a aria-label=\"Facebook\" class=\"heateor_sss_facebook\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2017%2F12%2F20%2Fquando-confliggono-diritto-interno-e-diritto-ue-una-sentenza-della-corte%2F\" title=\"Facebook\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#0765FE;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path fill=\"#fff\" d=\"M28 16c0-6.627-5.373-12-12-12S4 9.373 4 16c0 5.628 3.875 10.35 9.101 11.647v-7.98h-2.474V16H13.1v-1.58c0-4.085 1.849-5.978 5.859-5.978.76 0 2.072.15 2.608.298v3.325c-.283-.03-.775-.045-1.386-.045-1.967 0-2.728.745-2.728 2.683V16h3.92l-.673 3.667h-3.247v8.245C23.395 27.195 28 22.135 28 16Z\"><\/path><\/svg><\/span><\/a><a aria-label=\"Twitter\" class=\"heateor_sss_button_twitter\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Quando%20confliggono%20diritto%20interno%20e%20diritto%20Ue%3A%20una%20sentenza%20della%20Corte&url=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2017%2F12%2F20%2Fquando-confliggono-diritto-interno-e-diritto-ue-una-sentenza-della-corte%2F\" title=\"Twitter\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_twitter\" style=\"background-color:#55acee;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 39 39\"><path d=\"M28 8.557a9.913 9.913 0 0 1-2.828.775 4.93 4.93 0 0 0 2.166-2.725 9.738 9.738 0 0 1-3.13 1.194 4.92 4.92 0 0 0-3.593-1.55 4.924 4.924 0 0 0-4.794 6.049c-4.09-.21-7.72-2.17-10.15-5.15a4.942 4.942 0 0 0-.665 2.477c0 1.71.87 3.214 2.19 4.1a4.968 4.968 0 0 1-2.23-.616v.06c0 2.39 1.7 4.38 3.952 4.83-.414.115-.85.174-1.297.174-.318 0-.626-.03-.928-.086a4.935 4.935 0 0 0 4.6 3.42 9.893 9.893 0 0 1-6.114 2.107c-.398 0-.79-.023-1.175-.068a13.953 13.953 0 0 0 7.55 2.213c9.056 0 14.01-7.507 14.01-14.013 0-.213-.005-.426-.015-.637.96-.695 1.795-1.56 2.455-2.55z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a aria-label=\"Reddit\" class=\"heateor_sss_button_reddit\" href=\"https:\/\/reddit.com\/submit?url=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2017%2F12%2F20%2Fquando-confliggono-diritto-interno-e-diritto-ue-una-sentenza-della-corte%2F&title=Quando%20confliggono%20diritto%20interno%20e%20diritto%20Ue%3A%20una%20sentenza%20della%20Corte\" title=\"Reddit\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_reddit\" style=\"background-color:#ff5700;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-3.5 -3.5 39 39\"><path d=\"M28.543 15.774a2.953 2.953 0 0 0-2.951-2.949 2.882 2.882 0 0 0-1.9.713 14.075 14.075 0 0 0-6.85-2.044l1.38-4.349 3.768.884a2.452 2.452 0 1 0 .24-1.176l-4.274-1a.6.6 0 0 0-.709.4l-1.659 5.224a14.314 14.314 0 0 0-7.316 2.029 2.908 2.908 0 0 0-1.872-.681 2.942 2.942 0 0 0-1.618 5.4 5.109 5.109 0 0 0-.062.765c0 4.158 5.037 7.541 11.229 7.541s11.22-3.383 11.22-7.541a5.2 5.2 0 0 0-.053-.706 2.963 2.963 0 0 0 1.427-2.51zm-18.008 1.88a1.753 1.753 0 0 1 1.73-1.74 1.73 1.73 0 0 1 1.709 1.74 1.709 1.709 0 0 1-1.709 1.711 1.733 1.733 0 0 1-1.73-1.711zm9.565 4.968a5.573 5.573 0 0 1-4.081 1.272h-.032a5.576 5.576 0 0 1-4.087-1.272.6.6 0 0 1 .844-.854 4.5 4.5 0 0 0 3.238.927h.032a4.5 4.5 0 0 0 3.237-.927.6.6 0 1 1 .844.854zm-.331-3.256a1.726 1.726 0 1 1 1.709-1.712 1.717 1.717 0 0 1-1.712 1.712z\" fill=\"#fff\"\/><\/svg><\/span><\/a><a aria-label=\"Linkedin\" class=\"heateor_sss_button_linkedin\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2017%2F12%2F20%2Fquando-confliggono-diritto-interno-e-diritto-ue-una-sentenza-della-corte%2F\" title=\"Linkedin\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_linkedin\" style=\"background-color:#0077b5;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path d=\"M6.227 12.61h4.19v13.48h-4.19V12.61zm2.095-6.7a2.43 2.43 0 0 1 0 4.86c-1.344 0-2.428-1.09-2.428-2.43s1.084-2.43 2.428-2.43m4.72 6.7h4.02v1.84h.058c.56-1.058 1.927-2.176 3.965-2.176 4.238 0 5.02 2.792 5.02 6.42v7.395h-4.183v-6.56c0-1.564-.03-3.574-2.178-3.574-2.18 0-2.514 1.7-2.514 3.46v6.668h-4.187V12.61z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a aria-label=\"Pinterest\" class=\"heateor_sss_button_pinterest\" href=\"https:\/\/www.lacostituzione.info\/index.php\/2017\/12\/20\/quando-confliggono-diritto-interno-e-diritto-ue-una-sentenza-della-corte\/\" onclick=\"event.preventDefault();javascript:void( (function() {var e=document.createElement('script' );e.setAttribute('type','text\/javascript' );e.setAttribute('charset','UTF-8' );e.setAttribute('src','\/\/assets.pinterest.com\/js\/pinmarklet.js?r='+Math.random()*99999999);document.body.appendChild(e)})());\" title=\"Pinterest\" rel=\"noopener\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_pinterest\" style=\"background-color:#cc2329;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-2 -2 35 35\"><path fill=\"#fff\" d=\"M16.539 4.5c-6.277 0-9.442 4.5-9.442 8.253 0 2.272.86 4.293 2.705 5.046.303.125.574.005.662-.33.061-.231.205-.816.27-1.06.088-.331.053-.447-.191-.736-.532-.627-.873-1.439-.873-2.591 0-3.338 2.498-6.327 6.505-6.327 3.548 0 5.497 2.168 5.497 5.062 0 3.81-1.686 7.025-4.188 7.025-1.382 0-2.416-1.142-2.085-2.545.397-1.674 1.166-3.48 1.166-4.689 0-1.081-.581-1.983-1.782-1.983-1.413 0-2.548 1.462-2.548 3.419 0 1.247.421 2.091.421 2.091l-1.699 7.199c-.505 2.137-.076 4.755-.039 5.019.021.158.223.196.314.077.13-.17 1.813-2.247 2.384-4.324.162-.587.929-3.631.929-3.631.46.876 1.801 1.646 3.227 1.646 4.247 0 7.128-3.871 7.128-9.053.003-3.918-3.317-7.568-8.361-7.568z\"\/><\/svg><\/span><\/a><a aria-label=\"Whatsapp\" class=\"heateor_sss_whatsapp\" href=\"https:\/\/api.whatsapp.com\/send?text=Quando%20confliggono%20diritto%20interno%20e%20diritto%20Ue%3A%20una%20sentenza%20della%20Corte%20https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2017%2F12%2F20%2Fquando-confliggono-diritto-interno-e-diritto-ue-una-sentenza-della-corte%2F\" title=\"Whatsapp\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#55eb4c;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-6 -5 40 40\"><path class=\"heateor_sss_svg_stroke heateor_sss_no_fill\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\" d=\"M 11.579798566743314 24.396926207859085 A 10 10 0 1 0 6.808479557110079 20.73576436351046\"><\/path><path d=\"M 7 19 l -1 6 l 6 -1\" class=\"heateor_sss_no_fill heateor_sss_svg_stroke\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\"><\/path><path d=\"M 10 10 q -1 8 8 11 c 5 -1 0 -6 -1 -3 q -4 -3 -5 -5 c 4 -2 -1 -5 -1 -4\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><\/div><div class=\"heateorSssClear\"><\/div><\/div><div class='heateorSssClear'><\/div>","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"enabled":false},"version":2}},"categories":[4],"tags":[459,940,149,74,941],"class_list":["post-3396","post","type-post","status-publish","format-standard","hentry","category-attualita","tag-carta-dei-diritti-fondamentali-ue","tag-carta-di-nizza","tag-corte-costituzionale","tag-costituzione","tag-trattati-di-lisbona"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p84sDq-SM","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/posts\/3396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/comments?post=3396"}],"version-history":[{"count":0,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/posts\/3396\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/media?parent=3396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/categories?post=3396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/tags?post=3396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}