{"id":5693,"date":"2018-09-11T23:52:32","date_gmt":"2018-09-11T21:52:32","guid":{"rendered":"http:\/\/www.lacostituzione.info\/?p=5693"},"modified":"2018-09-12T20:27:41","modified_gmt":"2018-09-12T18:27:41","slug":"100-giorni-di-governo","status":"publish","type":"post","link":"https:\/\/www.lacostituzione.info\/index.php\/2018\/09\/11\/100-giorni-di-governo\/","title":{"rendered":"100 giorni di governo Conte in parlamento: i dati"},"content":{"rendered":"<p><a href=\"http:\/\/www.lacostituzione.info\/wp-content\/uploads\/2018\/07\/camera.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"5420\" data-permalink=\"https:\/\/www.lacostituzione.info\/index.php\/2018\/07\/07\/lesame-del-bilancio-camera-dalla-routine-amministrativa-allo-scontro-politico\/camera\/#main\" data-orig-file=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2018\/07\/camera.jpg\" data-orig-size=\"620,350\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"camera\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2018\/07\/camera-300x169.jpg\" data-large-file=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2018\/07\/camera.jpg\" class=\"alignright size-thumbnail wp-image-5420\" src=\"http:\/\/www.lacostituzione.info\/wp-content\/uploads\/2018\/07\/camera-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>di\u00a0<strong>Gianluca De Filio<\/strong><\/p>\n<p>Il governo Conte ha iniziato la sua avventura parlamentare il 5 giugno con lo svolgimento delle dichiarazioni programmatiche del presidente del consiglio alle Camere.<!--more--><\/p>\n<p>Poich\u00e9 siamo ormai al traguardo dei fatidici cento giorni \u00e8 opportuno fare un bilancio dell\u2019attivit\u00e0 del governo in sede parlamentare.<\/p>\n<p>Dal 5 giugno il governo ha varato 6 decreti legge depositando in parlamento altrettanti disegni di legge di conversione. Di questi solo 1 pu\u00f2 essere considerato un provvedimento di natura politica finalizzato all\u2019attuazione del programma di governo: il Dl 87\/2018, comunemente detto decreto dignit\u00e0, che \u00e8 intervenuto a modificare parti della normativa vigente in materia di contratti di lavoro a tempo determinato, delocalizzazioni e crisi aziendali, nonch\u00e9 in materia di gioco d\u2019azzardo.<\/p>\n<p>Quattro decreti legge hanno avuto invece portata ristretta e limitata: come il decreto legge finalizzato a garantire lo svolgimento dei processi penali nel tribunale di Bari (Dl 73\/2018) adottato sulla scorta dell\u2019emergenza prodottasi a seguito dell\u2019inagibilit\u00e0 delle strutture che ospitavano il tribunale del capoluogo pugliese; il decreto legge sul riordino delle competenze dei ministeri (Dl 86\/2018) che ha risposto ad esigenze di bilanciamento delle competenze politiche interne alla compagine di governo; il decreto legge che ha disposto la cessione alla Libia di alcune unit\u00e0 navali della nostra marina (Dl 84\/2018); ed infine il decreto legge che disponeva la proroga per l\u2019entrata in vigore della fatturazione elettronica per le cessioni di carburante (Dl 79\/2018);<\/p>\n<p>L\u2019ultimo dei sei decreti varati dal governo \u00e8 l\u2019annuale milleproroghe (Dl. 91\/2018) che, a differenza degli anni precedenti, \u00e8 stato anticipato all\u2019estate, anzich\u00e9 vararlo alla fine dell\u2019anno.<\/p>\n<p>Di questi decreti legge 4 sono stati convertiti in legge dalle Camere, uno quello sulla fatturazione elettronica \u00e8 stato fatto decadere perch\u00e9 il suo contenuto \u00e8 stato inserito con un emendamento all\u2019interno del decreto dignit\u00e0. Il decreto milleproroghe \u00e8 ancora in corso di approvazione.<\/p>\n<p>In ordine all\u2019esame di conversione dei decreti legge il governo Conte ha, almeno fino ad oggi, fatto registrare una significativa novit\u00e0, quella di non aver mai fatto ricorso all\u2019apposizione della questione di fiducia tecnica (finalizzate ad accelerare l\u2019approvazione del provvedimento nell\u2019esame d\u2019aula interdicendo la votazione di tutti gli emendamenti presentati).<\/p>\n<p>Sempre in ordine all\u2019approvazione dei disegni di legge di conversione, le modifiche ai testi dei decreti sono state consentite in una sola delle due Camere, con l\u2019approvazione definitiva e senza modifiche da parte della camera che procedeva alla seconda lettura.<\/p>\n<p>A questa tendenza si sottrarr\u00e0 il decreto milleproroghe che, dopo essere stato modificato in prima lettura al Senato, \u00e8 stato ulteriormente modificato in commissione alla Camera, imponendo dunque una terza lettura al Senato.<\/p>\n<p>Per quanto riguarda l\u2019ulteriore attivit\u00e0 legislativa di iniziativa governativa il governo ha presentato 8 disegni di legge di ratifica di trattati internazionale (tutti approvati), e i disegni di legge di assestamento del bilancio 2018 e del rendiconto dello stato per l\u2019anno 2017, che ad oggi non sono stati ancora approvati.<\/p>\n<p>Per quanto riguarda gli ulteriori documenti inerenti la manovra di finanza pubblica, anche per la tempistica della sua formazione, il governo Conte non ha presentato un suo Def, limitandosi a far approvare il Def scritto a legislazione vigente dal governo Gentiloni e, per giunta, concordando con la propria maggioranza una risoluzione estremamente timida che di fatto si limita ad imporre la sola sterilizzazione dell\u2019aumento dell\u2019Iva prevista per il 2019.<\/p>\n<p>Politicamente, almeno fino ad oggi, sembra emergere una tendenza del governo a demandare a disegni di legge di iniziativa parlamentare, che per\u00f2 non hanno ancora iniziato il proprio iter, la realizzazione delle parti pi\u00f9 problematiche del programma di governo (pensioni d\u2019oro, vaccini, riforma dell\u2019affido dei figli, chiusure domenicali degli esercizi commerciali). Lo stesso provvedimento anticorruzione, approvato salvo intese nel cdm del 6 settembre e non ancora depositato alle camere, \u00e8 un disegno di legge e non un decreto legge.<\/p>\n<p>Il presidente del Consiglio Conte, dal momento del suo insediamento ha messo piede in parlamento soltanto in tre occasioni: quella della prima votazione di fiducia al suo governo, il 27 giugno in occasione delle comunicazioni rese in vista del Consiglio Europeo del 28 e 29 giugno e da ultimo mercoled\u00ec 12 settembre per prendere parte al \u201cpremier question time\u201d alla Camera dei deputati.<\/p>\n<p>Con altri suoi rappresentanti il governo ha reso altre tre informative urgenti (il 13\/6 in Senato sulla vicenda della nave Aquarius, il 14\/6 alla Camera sugli incidenti nei luoghi di lavoro e il 18\/7 alla Camera sui tavoli di crisi aperti presso il Mise), ed una comunicazione, resa il 4 settembre alla Camera, sul crollo del ponte Morandi di Genova.<\/p>\n<p>Anche nello svolgimento delle informative, forse perch\u00e9 in tre casi su quattro sono state svolte dai vice presidenti del consiglio Di Maio e Salvini, il governo ha fatto registrare una novit\u00e0 nello stile di tali comunicazioni. Se di solito le informative urgenti consistono in un\u2019elencazione abbastanza formale e burocratica di fatti e dati inerenti la vicenda oggetto dell\u2019informativa, quelle rese dai due vice presidenti del consiglio (ma anche le comunicazioni del Ministro Toninelli) hanno assunto un carattere pi\u00f9 generico per quanto riguarda i dati e pi\u00f9 politico per le argomentazioni svolte, che in alcuni casi hanno fatto pensare pi\u00f9 ad un discorso politico rivolto all\u2019esterno che all\u2019interno del parlamento.<\/p>\n<p>Per quanto riguarda la presenza in aula, il governo \u00e8 intervenuto a sei sedute di <em>question time<\/em> alla Camera dei deputati (rispettando la cadenza canonica di una volta a settimana) e a due al Senato (12 e 27 luglio), dove il <em>question time<\/em> \u00e8 stato introdotto in questa legislatura e a seguito della riforma del regolamento.<\/p>\n<p>Il governo ha inoltre dato risposta a 310 atti di sindacato ispettivo (247 presentati alla Camera e 63 presentati al senato) su circa 1600 atti depositati.<\/p>\n<p>Volendo tirare delle conclusioni, l\u2019impressione che emerge da questi primi tre mesi di attivit\u00e0 parlamentare \u00e8 quella di un governo che pu\u00f2 contare su una maggioranza che quando \u00e8 stata chiamata\u00a0 in causa \u00e8 apparsa compatta e affidabile: un motore che, per il momento, sembra poter sostenere una buona velocit\u00e0, ma che sovente viene fatto girare a vuoto o mantenuto al regime minimo perch\u00e9 il guidatore, in alcuni casi, non sembra avere chiaro quali siano le strade da percorrere.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>di\u00a0Gianluca De Filio Il governo Conte ha iniziato la sua avventura parlamentare il 5 giugno con lo svolgimento delle dichiarazioni programmatiche del presidente del consiglio alle Camere.<\/p>\n<div class='heateorSssClear'><\/div><div  class='heateor_sss_sharing_container heateor_sss_horizontal_sharing' data-heateor-sss-href='https:\/\/www.lacostituzione.info\/index.php\/2018\/09\/11\/100-giorni-di-governo\/'><div class='heateor_sss_sharing_title' style=\"font-weight:bold\" >Condividi!<\/div><div class=\"heateor_sss_sharing_ul\"><a aria-label=\"Facebook\" class=\"heateor_sss_facebook\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2018%2F09%2F11%2F100-giorni-di-governo%2F\" title=\"Facebook\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#0765FE;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path fill=\"#fff\" d=\"M28 16c0-6.627-5.373-12-12-12S4 9.373 4 16c0 5.628 3.875 10.35 9.101 11.647v-7.98h-2.474V16H13.1v-1.58c0-4.085 1.849-5.978 5.859-5.978.76 0 2.072.15 2.608.298v3.325c-.283-.03-.775-.045-1.386-.045-1.967 0-2.728.745-2.728 2.683V16h3.92l-.673 3.667h-3.247v8.245C23.395 27.195 28 22.135 28 16Z\"><\/path><\/svg><\/span><\/a><a aria-label=\"Twitter\" class=\"heateor_sss_button_twitter\" href=\"https:\/\/twitter.com\/intent\/tweet?text=100%20giorni%20di%20governo%20Conte%20in%20parlamento%3A%20i%20dati&url=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2018%2F09%2F11%2F100-giorni-di-governo%2F\" title=\"Twitter\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_twitter\" style=\"background-color:#55acee;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 39 39\"><path d=\"M28 8.557a9.913 9.913 0 0 1-2.828.775 4.93 4.93 0 0 0 2.166-2.725 9.738 9.738 0 0 1-3.13 1.194 4.92 4.92 0 0 0-3.593-1.55 4.924 4.924 0 0 0-4.794 6.049c-4.09-.21-7.72-2.17-10.15-5.15a4.942 4.942 0 0 0-.665 2.477c0 1.71.87 3.214 2.19 4.1a4.968 4.968 0 0 1-2.23-.616v.06c0 2.39 1.7 4.38 3.952 4.83-.414.115-.85.174-1.297.174-.318 0-.626-.03-.928-.086a4.935 4.935 0 0 0 4.6 3.42 9.893 9.893 0 0 1-6.114 2.107c-.398 0-.79-.023-1.175-.068a13.953 13.953 0 0 0 7.55 2.213c9.056 0 14.01-7.507 14.01-14.013 0-.213-.005-.426-.015-.637.96-.695 1.795-1.56 2.455-2.55z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a aria-label=\"Reddit\" class=\"heateor_sss_button_reddit\" href=\"https:\/\/reddit.com\/submit?url=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2018%2F09%2F11%2F100-giorni-di-governo%2F&title=100%20giorni%20di%20governo%20Conte%20in%20parlamento%3A%20i%20dati\" title=\"Reddit\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_reddit\" style=\"background-color:#ff5700;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-3.5 -3.5 39 39\"><path d=\"M28.543 15.774a2.953 2.953 0 0 0-2.951-2.949 2.882 2.882 0 0 0-1.9.713 14.075 14.075 0 0 0-6.85-2.044l1.38-4.349 3.768.884a2.452 2.452 0 1 0 .24-1.176l-4.274-1a.6.6 0 0 0-.709.4l-1.659 5.224a14.314 14.314 0 0 0-7.316 2.029 2.908 2.908 0 0 0-1.872-.681 2.942 2.942 0 0 0-1.618 5.4 5.109 5.109 0 0 0-.062.765c0 4.158 5.037 7.541 11.229 7.541s11.22-3.383 11.22-7.541a5.2 5.2 0 0 0-.053-.706 2.963 2.963 0 0 0 1.427-2.51zm-18.008 1.88a1.753 1.753 0 0 1 1.73-1.74 1.73 1.73 0 0 1 1.709 1.74 1.709 1.709 0 0 1-1.709 1.711 1.733 1.733 0 0 1-1.73-1.711zm9.565 4.968a5.573 5.573 0 0 1-4.081 1.272h-.032a5.576 5.576 0 0 1-4.087-1.272.6.6 0 0 1 .844-.854 4.5 4.5 0 0 0 3.238.927h.032a4.5 4.5 0 0 0 3.237-.927.6.6 0 1 1 .844.854zm-.331-3.256a1.726 1.726 0 1 1 1.709-1.712 1.717 1.717 0 0 1-1.712 1.712z\" fill=\"#fff\"\/><\/svg><\/span><\/a><a aria-label=\"Linkedin\" class=\"heateor_sss_button_linkedin\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2018%2F09%2F11%2F100-giorni-di-governo%2F\" title=\"Linkedin\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_linkedin\" style=\"background-color:#0077b5;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path d=\"M6.227 12.61h4.19v13.48h-4.19V12.61zm2.095-6.7a2.43 2.43 0 0 1 0 4.86c-1.344 0-2.428-1.09-2.428-2.43s1.084-2.43 2.428-2.43m4.72 6.7h4.02v1.84h.058c.56-1.058 1.927-2.176 3.965-2.176 4.238 0 5.02 2.792 5.02 6.42v7.395h-4.183v-6.56c0-1.564-.03-3.574-2.178-3.574-2.18 0-2.514 1.7-2.514 3.46v6.668h-4.187V12.61z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a aria-label=\"Pinterest\" class=\"heateor_sss_button_pinterest\" href=\"https:\/\/www.lacostituzione.info\/index.php\/2018\/09\/11\/100-giorni-di-governo\/\" onclick=\"event.preventDefault();javascript:void( (function() {var e=document.createElement('script' );e.setAttribute('type','text\/javascript' );e.setAttribute('charset','UTF-8' );e.setAttribute('src','\/\/assets.pinterest.com\/js\/pinmarklet.js?r='+Math.random()*99999999);document.body.appendChild(e)})());\" title=\"Pinterest\" rel=\"noopener\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_pinterest\" style=\"background-color:#cc2329;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-2 -2 35 35\"><path fill=\"#fff\" d=\"M16.539 4.5c-6.277 0-9.442 4.5-9.442 8.253 0 2.272.86 4.293 2.705 5.046.303.125.574.005.662-.33.061-.231.205-.816.27-1.06.088-.331.053-.447-.191-.736-.532-.627-.873-1.439-.873-2.591 0-3.338 2.498-6.327 6.505-6.327 3.548 0 5.497 2.168 5.497 5.062 0 3.81-1.686 7.025-4.188 7.025-1.382 0-2.416-1.142-2.085-2.545.397-1.674 1.166-3.48 1.166-4.689 0-1.081-.581-1.983-1.782-1.983-1.413 0-2.548 1.462-2.548 3.419 0 1.247.421 2.091.421 2.091l-1.699 7.199c-.505 2.137-.076 4.755-.039 5.019.021.158.223.196.314.077.13-.17 1.813-2.247 2.384-4.324.162-.587.929-3.631.929-3.631.46.876 1.801 1.646 3.227 1.646 4.247 0 7.128-3.871 7.128-9.053.003-3.918-3.317-7.568-8.361-7.568z\"\/><\/svg><\/span><\/a><a aria-label=\"Whatsapp\" class=\"heateor_sss_whatsapp\" href=\"https:\/\/api.whatsapp.com\/send?text=100%20giorni%20di%20governo%20Conte%20in%20parlamento%3A%20i%20dati%20https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2018%2F09%2F11%2F100-giorni-di-governo%2F\" title=\"Whatsapp\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#55eb4c;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-6 -5 40 40\"><path class=\"heateor_sss_svg_stroke heateor_sss_no_fill\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\" d=\"M 11.579798566743314 24.396926207859085 A 10 10 0 1 0 6.808479557110079 20.73576436351046\"><\/path><path d=\"M 7 19 l -1 6 l 6 -1\" class=\"heateor_sss_no_fill heateor_sss_svg_stroke\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\"><\/path><path d=\"M 10 10 q -1 8 8 11 c 5 -1 0 -6 -1 -3 q -4 -3 -5 -5 c 4 -2 -1 -5 -1 -4\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><\/div><div class=\"heateorSssClear\"><\/div><\/div><div class='heateorSssClear'><\/div>","protected":false},"author":20,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"enabled":false},"version":2}},"categories":[4],"tags":[1308,1286,113],"class_list":["post-5693","post","type-post","status-publish","format-standard","hentry","category-attualita","tag-100-giorni","tag-governo-conte","tag-parlamento"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p84sDq-1tP","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/posts\/5693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/comments?post=5693"}],"version-history":[{"count":0,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/posts\/5693\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/media?parent=5693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/categories?post=5693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/tags?post=5693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}