{"id":7283,"date":"2020-08-27T10:00:31","date_gmt":"2020-08-27T08:00:31","guid":{"rendered":"http:\/\/www.lacostituzione.info\/?p=7283"},"modified":"2020-08-27T10:00:33","modified_gmt":"2020-08-27T08:00:33","slug":"contro-la-retorica-delle-riforme-epocali","status":"publish","type":"post","link":"https:\/\/www.lacostituzione.info\/index.php\/2020\/08\/27\/contro-la-retorica-delle-riforme-epocali\/","title":{"rendered":"Contro la retorica delle \u2018riforme\u2019 epocali"},"content":{"rendered":"\n<p><a href=\"http:\/\/www.lacostituzione.info\/wp-content\/uploads\/2020\/08\/referendum.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7260\" data-permalink=\"https:\/\/www.lacostituzione.info\/index.php\/2020\/08\/22\/taglio-dei-parlamentari-si-o-no-per-promuovere-un-dibattito\/referendum-2\/#main\" data-orig-file=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2020\/08\/referendum.jpg\" data-orig-size=\"300,250\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"referendum\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2020\/08\/referendum-300x250.jpg\" data-large-file=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2020\/08\/referendum.jpg\" class=\"alignleft size-thumbnail wp-image-7260\" src=\"http:\/\/www.lacostituzione.info\/wp-content\/uploads\/2020\/08\/referendum-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>di\u00a0<strong>Andrea Venanzoni<\/strong><\/p>\n<p><strong>\u00a0<\/strong>A rilegger oggi le pagine di un agile librino di Ugo Mattei, apparso nel 2013 per i tipi di Einaudi, <em>Contro riforme<\/em>, alla luce dell\u2019incombente referendum costituzionale settembrino, inopinatamente accorpato al voto regionale, verrebbe da dire che il \u2018riformismo\u2019 alla italiana si sta ormai avvitando in una crisi, accelerata e sempre meno meditata, che porta alla coazione a voler sfornare progetti, pi\u00f9 o meno venduti alla opinione pubblica come epocali, senza pensare per\u00f2 di voler suscitare il men che minimo dibattito nella opinione pubblica.<!--more--><\/p>\n<p>Il feticismo riformista che involge tanto i singoli settori legislativi, quanto l\u2019azione e l\u2019organizzazione amministrative, non riesce pi\u00f9 a risparmiare nemmeno la Costituzione, tirata metaforicamente per la giacchetta poich\u00e9 ciascuno sembra desideroso di mettervi sopra il proprio timbro, a colpi di maggioranza, in spregio alla <em>ratio<\/em> vitale di un patto costituzionale.<\/p>\n<p>Almeno, nella passata e tutto sommata recente ipotesi di riforma costituzionale respinta in sede referendaria nel dicembre 2016, non vi furono solo statici <em>input<\/em> dati in pasto alla opinione pubblica ma si registr\u00f2 un certo dibattito, informato, interessato, vivo, che oscillava dai mezzi di stampa agli incontri organizzati da associazioni, fondazioni, persino Chiese e oratori. Si formarono in quella occasione convincimenti, opinioni, ed era possibile riscontrare posizioni estremamente meditate e organiche tanto in un fronte quanto nell\u2019altro.<\/p>\n<p>Non manc\u00f2 un certo grado di fideistico messianismo politico che rivest\u00ec, inopinatamente, l\u2019intero impianto riformistico di una patina semi-plebiscitaria tesa a confermare o smentire non pi\u00f9 la riforma quanto l\u2019azione politica complessiva di chi quella riforma aveva proposto.<\/p>\n<p>E se quello fu il limite evidente di quella tornata referendaria, lo stesso non imped\u00ec un certo grado di maturazione della opinione pubblica e della societ\u00e0 civile. In quel caso la stessa scienza giuridica si divise su posizioni meno assolutizzanti e anche da un punto di vista prettamente quantitativo non era arduo imbattersi in costituzionalisti che caldeggiassero la riforma e in altri che la avversassero con pari intensit\u00e0.<\/p>\n<p>Nel caso attuale, quasi il nulla.\u00a0Ne discutono i giuristi, in uno spazio in cui le ragioni del no sono prevalenti per motivazioni auto-evidenti, ma la societ\u00e0 civile \u00e8 cristallizzata in un silenzio che rende il voto stesso una sorta di curiosa parentesi incistata, quasi per caso, nel fianco del vero voto che sta animando il dibattito politico contemporaneo, il voto regionale.<\/p>\n<p>Ed \u00e8 piuttosto paradossale, ma segno dei tempi, che il voto regionale sia, nel dibattito pubblico, ormai assurto a forma di validazione o di sconfessione delle politiche attuate dal Governo, mentre la riforma costituzionale se ne rimane in un cantuccio, in penombra.<\/p>\n<p>A dire il vero, la liquefazione delle dinamiche parlamentari e il significativo <em>detour<\/em> delle fonti del diritto importati entrambi dalla crisi pandemica, con una iper-centralizzazione della azione governativa nelle mani del solo Presidente del Consiglio, importa una considerazione pi\u00f9 che preoccupante del significato non solo simbolico, ma anche strettamente sostanziale, della \u2018riforma\u2019, e di una sua certa aura punitiva nei confronti del momento parlamentare,\u00a0 non visto e considerato pi\u00f9 solo come inefficace, tortuoso, lento ma anche come eccedente rispetto alle presunte, \u2018vere\u2019 istanze del popolo.<\/p>\n<p>Sulla rappresentanza parlamentare giudicata con fastidio dai sostenitori della \u2018democrazia diretta\u2019 pi\u00f9 o meno digitale vi sono pochi dubbi, come ha giustamente rilevato Francesco Contini nel suo intervento del 22 Agosto e come si sostiene nel documento a favore del no firmato ad oggi da 183 costituzionalisti: basterebbe considerare le parole utilizzate per sostenere la riforma, tutte mirate al disvalore, alla sfiducia nei confronti del parlamentare, considerato come un soggetto da sottoporre a penetrante controllo dal \u2018popolo\u2019 per comprendere come la logica punitiva non sia un abbaglio ermeneutico, ma un dato di fatto.<\/p>\n<p>L\u2019agghiacciante espressione <em>taglio delle poltrone<\/em>, figlia di un giacobinismo digitale senza la caratura culturale del giacobinismo, i rimandi ai presunti risparmi epocali di spesa, corrispondenti in realt\u00e0 al valore di un caff\u00e8 (cito il medesimo esempio che gli attuali sostenitori politici del si utilizzavano quando erano impegnati a caldeggiare il no alla riforma Renzi-Boschi, asserendo all\u2019epoca che la Costituzione non si svende per un caff\u00e8) finiscono per obliare le risultanti pi\u00f9 patenti di una \u2018riforma\u2019 del genere; balcanizzazione frammentaria della rappresentanza parlamentare su base territoriale, asimmetrie interne ai lavori parlamentari, Commissioni comprese, eccesso di saturazione dei problemi tipologici del bicameralismo perfetto.<\/p>\n<p>In un incredibile volantino a sostegno delle ragioni del si ideato da una deputata del principale partito sostenitore della riforma, e <em>more solito<\/em> diffuso sui social, si legge \u201c<em>ogni parlamentare rappresenter\u00e0 un maggior numero di elettori e quindi sar\u00e0 molto pi\u00f9 visibile e di conseguenza pi\u00f9 responsabile e controllabile<\/em>\u201d.<\/p>\n<p>L\u2019ansia contro-democratica, per dirla alla Rosanvallon, non \u00e8 di certo, senza regole chiare, il miglior viatico per proporre riforme tese alla sorveglianza continua del parlamentare.\u00a0E soprattutto in tema di rappresentanza, sposando quel genere di logica potremmo anche sostenere che al fine di massimizzare davvero questa funzione di maggiore rappresentanza e di potenziale maggior responsabilizzazione degli eletti, i parlamentari potrebbero anche essere ridotti a uno solo. Oppure potrebbero essere direttamente sostituiti dal Presidente del Consiglio.<\/p>\n<p>Il \u2018politico\u2019 come <em>summa<\/em> del disvalore, del disfacimento della volont\u00e0 popolare, o generale, la rappresentanza stessa considerata come una macchina ornamentale inutile finiscono per riecheggiare quanto sosteneva a piena ragione Carl Schmitt, <em>\u201cil fatto di definire il nemico come politico e se stessi come non-politici (cio\u00e8 come scientifici, giusti, obbiettivi, imparziali ecc.) costituisce proprio un modo tipico e particolarmente intensivo di far politica\u201d.<\/em><\/p>\n<p>La Costituzione in questa chiave di lettura non \u00e8 pi\u00f9 patto, progetto politico comune, ma spazio di potenziale aggressione e di \u2018inimicizia\u2019, strumento <em>politico<\/em> di una parte.<\/p>\n<p>Il punto \u00e8 che ad oggi molte delle ragioni del si, le ragioni serie intendo e non quelle da arena mediatica, sono forzosamente ricondotte a una dimensione puramente ipotetica.\u00a0Valerio Onida ha ad esempio affermato che con il si le Camere <em>potrebbero<\/em> funzionare meglio. Il problema \u00e8 che mettere mano alla Costituzione, per altro in un modo che per metodo e sostanza lascia molti dubbi, senza aver ridisegnato in maniera <em>contestuale<\/em>, organicamente e coerentemente, \u00a0l\u2019architettura complessiva, a partire dalla legge elettorale, finisce per relegare gli effetti positivi al mero condizionale e al periodo ipotetico, mentre evidenzia per certe le storture che la \u2018riforma\u2019 importer\u00e0.<\/p>\n<p>Anche ripercorrendo le motivazioni favorevoli alla \u2018riforma\u2019 espresse a partire dall\u2019ottobre 2019 da Stefano Ceccanti si coglie la esigenza di una riforma pi\u00f9 organica, coerente e razionale: non a caso lo stesso Ceccanti, in suo articolo apparso il 7 Ottobre 2019 sulle pagine de Il Foglio, collegava questa \u2018riforma\u2019 a un disegno istituzionale pi\u00f9 ampio, stabilendo un parallelismo con la precedente riforma mancata, quella del 2016.<\/p>\n<p>Il problema \u00e8 che il disegno istituzionale pi\u00f9 organico ad oggi non c\u2019\u00e8 e non se ne scorge la fisionomia lungo la linea d\u2019orizzonte. Rimane, purtroppo, solo la retorica del <em>taglio delle poltrone<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>di\u00a0Andrea Venanzoni \u00a0A rilegger oggi le pagine di un agile librino di Ugo Mattei, apparso nel 2013 per i tipi di Einaudi, Contro riforme, alla luce dell\u2019incombente referendum costituzionale settembrino, inopinatamente accorpato al voto regionale, verrebbe da dire che il \u2018riformismo\u2019 alla italiana si sta ormai avvitando in una crisi, accelerata e sempre meno meditata, &#8230; <a title=\"Contro la retorica delle \u2018riforme\u2019 epocali\" class=\"read-more\" href=\"https:\/\/www.lacostituzione.info\/index.php\/2020\/08\/27\/contro-la-retorica-delle-riforme-epocali\/\">Leggi tutto<\/a><\/p>\n<div class='heateorSssClear'><\/div><div  class='heateor_sss_sharing_container heateor_sss_horizontal_sharing' data-heateor-sss-href='https:\/\/www.lacostituzione.info\/index.php\/2020\/08\/27\/contro-la-retorica-delle-riforme-epocali\/'><div class='heateor_sss_sharing_title' style=\"font-weight:bold\" >Condividi!<\/div><div class=\"heateor_sss_sharing_ul\"><a aria-label=\"Facebook\" class=\"heateor_sss_facebook\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2020%2F08%2F27%2Fcontro-la-retorica-delle-riforme-epocali%2F\" title=\"Facebook\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#0765FE;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path fill=\"#fff\" d=\"M28 16c0-6.627-5.373-12-12-12S4 9.373 4 16c0 5.628 3.875 10.35 9.101 11.647v-7.98h-2.474V16H13.1v-1.58c0-4.085 1.849-5.978 5.859-5.978.76 0 2.072.15 2.608.298v3.325c-.283-.03-.775-.045-1.386-.045-1.967 0-2.728.745-2.728 2.683V16h3.92l-.673 3.667h-3.247v8.245C23.395 27.195 28 22.135 28 16Z\"><\/path><\/svg><\/span><\/a><a aria-label=\"Twitter\" class=\"heateor_sss_button_twitter\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Contro%20la%20retorica%20delle%20%E2%80%98riforme%E2%80%99%20epocali&url=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2020%2F08%2F27%2Fcontro-la-retorica-delle-riforme-epocali%2F\" title=\"Twitter\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_twitter\" style=\"background-color:#55acee;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 39 39\"><path d=\"M28 8.557a9.913 9.913 0 0 1-2.828.775 4.93 4.93 0 0 0 2.166-2.725 9.738 9.738 0 0 1-3.13 1.194 4.92 4.92 0 0 0-3.593-1.55 4.924 4.924 0 0 0-4.794 6.049c-4.09-.21-7.72-2.17-10.15-5.15a4.942 4.942 0 0 0-.665 2.477c0 1.71.87 3.214 2.19 4.1a4.968 4.968 0 0 1-2.23-.616v.06c0 2.39 1.7 4.38 3.952 4.83-.414.115-.85.174-1.297.174-.318 0-.626-.03-.928-.086a4.935 4.935 0 0 0 4.6 3.42 9.893 9.893 0 0 1-6.114 2.107c-.398 0-.79-.023-1.175-.068a13.953 13.953 0 0 0 7.55 2.213c9.056 0 14.01-7.507 14.01-14.013 0-.213-.005-.426-.015-.637.96-.695 1.795-1.56 2.455-2.55z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a aria-label=\"Reddit\" class=\"heateor_sss_button_reddit\" href=\"https:\/\/reddit.com\/submit?url=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2020%2F08%2F27%2Fcontro-la-retorica-delle-riforme-epocali%2F&title=Contro%20la%20retorica%20delle%20%E2%80%98riforme%E2%80%99%20epocali\" title=\"Reddit\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_reddit\" style=\"background-color:#ff5700;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-3.5 -3.5 39 39\"><path d=\"M28.543 15.774a2.953 2.953 0 0 0-2.951-2.949 2.882 2.882 0 0 0-1.9.713 14.075 14.075 0 0 0-6.85-2.044l1.38-4.349 3.768.884a2.452 2.452 0 1 0 .24-1.176l-4.274-1a.6.6 0 0 0-.709.4l-1.659 5.224a14.314 14.314 0 0 0-7.316 2.029 2.908 2.908 0 0 0-1.872-.681 2.942 2.942 0 0 0-1.618 5.4 5.109 5.109 0 0 0-.062.765c0 4.158 5.037 7.541 11.229 7.541s11.22-3.383 11.22-7.541a5.2 5.2 0 0 0-.053-.706 2.963 2.963 0 0 0 1.427-2.51zm-18.008 1.88a1.753 1.753 0 0 1 1.73-1.74 1.73 1.73 0 0 1 1.709 1.74 1.709 1.709 0 0 1-1.709 1.711 1.733 1.733 0 0 1-1.73-1.711zm9.565 4.968a5.573 5.573 0 0 1-4.081 1.272h-.032a5.576 5.576 0 0 1-4.087-1.272.6.6 0 0 1 .844-.854 4.5 4.5 0 0 0 3.238.927h.032a4.5 4.5 0 0 0 3.237-.927.6.6 0 1 1 .844.854zm-.331-3.256a1.726 1.726 0 1 1 1.709-1.712 1.717 1.717 0 0 1-1.712 1.712z\" fill=\"#fff\"\/><\/svg><\/span><\/a><a aria-label=\"Linkedin\" class=\"heateor_sss_button_linkedin\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2020%2F08%2F27%2Fcontro-la-retorica-delle-riforme-epocali%2F\" title=\"Linkedin\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_linkedin\" style=\"background-color:#0077b5;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path d=\"M6.227 12.61h4.19v13.48h-4.19V12.61zm2.095-6.7a2.43 2.43 0 0 1 0 4.86c-1.344 0-2.428-1.09-2.428-2.43s1.084-2.43 2.428-2.43m4.72 6.7h4.02v1.84h.058c.56-1.058 1.927-2.176 3.965-2.176 4.238 0 5.02 2.792 5.02 6.42v7.395h-4.183v-6.56c0-1.564-.03-3.574-2.178-3.574-2.18 0-2.514 1.7-2.514 3.46v6.668h-4.187V12.61z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a aria-label=\"Pinterest\" class=\"heateor_sss_button_pinterest\" href=\"https:\/\/www.lacostituzione.info\/index.php\/2020\/08\/27\/contro-la-retorica-delle-riforme-epocali\/\" onclick=\"event.preventDefault();javascript:void( (function() {var e=document.createElement('script' );e.setAttribute('type','text\/javascript' );e.setAttribute('charset','UTF-8' );e.setAttribute('src','\/\/assets.pinterest.com\/js\/pinmarklet.js?r='+Math.random()*99999999);document.body.appendChild(e)})());\" title=\"Pinterest\" rel=\"noopener\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_pinterest\" style=\"background-color:#cc2329;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-2 -2 35 35\"><path fill=\"#fff\" d=\"M16.539 4.5c-6.277 0-9.442 4.5-9.442 8.253 0 2.272.86 4.293 2.705 5.046.303.125.574.005.662-.33.061-.231.205-.816.27-1.06.088-.331.053-.447-.191-.736-.532-.627-.873-1.439-.873-2.591 0-3.338 2.498-6.327 6.505-6.327 3.548 0 5.497 2.168 5.497 5.062 0 3.81-1.686 7.025-4.188 7.025-1.382 0-2.416-1.142-2.085-2.545.397-1.674 1.166-3.48 1.166-4.689 0-1.081-.581-1.983-1.782-1.983-1.413 0-2.548 1.462-2.548 3.419 0 1.247.421 2.091.421 2.091l-1.699 7.199c-.505 2.137-.076 4.755-.039 5.019.021.158.223.196.314.077.13-.17 1.813-2.247 2.384-4.324.162-.587.929-3.631.929-3.631.46.876 1.801 1.646 3.227 1.646 4.247 0 7.128-3.871 7.128-9.053.003-3.918-3.317-7.568-8.361-7.568z\"\/><\/svg><\/span><\/a><a aria-label=\"Whatsapp\" class=\"heateor_sss_whatsapp\" href=\"https:\/\/api.whatsapp.com\/send?text=Contro%20la%20retorica%20delle%20%E2%80%98riforme%E2%80%99%20epocali%20https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2020%2F08%2F27%2Fcontro-la-retorica-delle-riforme-epocali%2F\" title=\"Whatsapp\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#55eb4c;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-6 -5 40 40\"><path class=\"heateor_sss_svg_stroke heateor_sss_no_fill\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\" d=\"M 11.579798566743314 24.396926207859085 A 10 10 0 1 0 6.808479557110079 20.73576436351046\"><\/path><path d=\"M 7 19 l -1 6 l 6 -1\" class=\"heateor_sss_no_fill heateor_sss_svg_stroke\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\"><\/path><path d=\"M 10 10 q -1 8 8 11 c 5 -1 0 -6 -1 -3 q -4 -3 -5 -5 c 4 -2 -1 -5 -1 -4\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><\/div><div class=\"heateorSssClear\"><\/div><\/div><div class='heateorSssClear'><\/div>","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"enabled":false},"version":2}},"categories":[14],"tags":[1451,1452],"class_list":["post-7283","post","type-post","status-publish","format-standard","hentry","category-di-robusta-costituzione","tag-referendum-costituzionale","tag-taglio-parlamentari"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p84sDq-1Tt","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/posts\/7283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/comments?post=7283"}],"version-history":[{"count":0,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/posts\/7283\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/media?parent=7283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/categories?post=7283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/tags?post=7283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}