{"id":8487,"date":"2022-10-06T12:57:59","date_gmt":"2022-10-06T10:57:59","guid":{"rendered":"http:\/\/www.lacostituzione.info\/?p=8487"},"modified":"2022-10-06T12:58:18","modified_gmt":"2022-10-06T10:58:18","slug":"la-nuova-disposizione-dei-seggi-una-questione-non-marginale-e-una-modesta-proposta","status":"publish","type":"post","link":"https:\/\/www.lacostituzione.info\/index.php\/2022\/10\/06\/la-nuova-disposizione-dei-seggi-una-questione-non-marginale-e-una-modesta-proposta\/","title":{"rendered":"La nuova disposizione dei seggi: una questione non marginale (e una modesta proposta)"},"content":{"rendered":"\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.lacostituzione.info\/index.php\/2022\/08\/20\/principio-maggioritario-finzioni-elettorali-e-vincolo-esterno\/senato_banchi_3_adn\/#main\" rel=\"attachment wp-att-7582\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7582\" data-permalink=\"https:\/\/www.lacostituzione.info\/index.php\/2022\/08\/20\/principio-maggioritario-finzioni-elettorali-e-vincolo-esterno\/senato_banchi_3_adn\/#main\" data-orig-file=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2021\/01\/senato_banchi_3_adn.jpg\" data-orig-size=\"750,501\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"senato_banchi_3_adn\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2021\/01\/senato_banchi_3_adn-300x200.jpg\" data-large-file=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2021\/01\/senato_banchi_3_adn.jpg\" class=\"size-thumbnail wp-image-7582 aligncenter\" src=\"http:\/\/www.lacostituzione.info\/wp-content\/uploads\/2021\/01\/senato_banchi_3_adn-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>di\u00a0<strong>Salvatore Curreri<\/strong><\/p>\n<p>Il Corriere della Sera d\u00e0 oggi conto, con tanto di foto, degli interventi strutturali che Camera e Senato stanno apportando alle file degli scranni a seguito della riduzione del numero dei rispettivi componenti (com\u2019\u00e8 noto da 630 a 400 deputati e da 315 a 200 senatori elettivi). <!--more-->Nello specifico, sembra che siano state eliminate le postazioni della prima e dell\u2019ultima fila e quelle pi\u00f9 laterali.<\/p>\n<p>La disposizione dei seggi e, pi\u00f9 in generale, la conformazione architettonica delle aule delle assemblee rappresentative \u00e8 questione tutt\u2019altro che marginale (v. F. Zagari, <em>La casa del Parlamento. Fra architettura, istituzioni e poteri<\/em>, in <em>Storia d\u2019Italia<\/em>. Annali 17. Il Parlamento, 2001, p. 977-1006).<\/p>\n<p>Del resto, per capire la differenza tra il sistema parlamentare maggioritario e quello consensuale basta osservare la diversa architettura delle Camere inglesi rispetto alle nostre. La Camera dei Comuni e la Camera dei <em>lords<\/em> sono rettangolari; maggioranza di governo ed opposizione, con i rispettivi <em>leader<\/em>, sono poste l\u2019una di fronte all\u2019altra; i due settori sono marcati da una linea rossa invalicabile e la distanza che li separa \u00e8 pari alla quella di due spade, le cui punte devono appena sfiorarsi, a significare che il confronto parlamentare pu\u00f2 e deve essere duro ma mai trascendere nell\u2019aggressione fisica dell\u2019avversario (tutto il parlamentarismo inglese \u00e8 carico di affascinanti simbolismi!). Questa disposizione non \u00e8 ovviamente casuale ma risponde alla caratteristiche di quella forma di governo, dove l\u2019esistenza di un sistema tendenzialmente bipartitico, diviso tra laburisti e conservatori accomunati per\u00f2 da una cultura politico-costituzionale omogenea, permette agli elettori di votare non solo per eleggere i propri rappresentanti nei singoli collegi uninominali ma anche per scegliere la maggioranza di governo, designando indirettamente come <em>Premier <\/em>il leader del partito vincente; e di contro l\u2019opposizione che ha il compito, non di sostituire il governo in corso di legislatura, ma di contrapporsi ad esso, attraverso la propria serrata attivit\u00e0 di controllo e di critica politica, allo scopo di proporsi come futura maggioranza alle prossime elezioni.<\/p>\n<p>Nel nostro paese, invece, Camera e Senato hanno una dimensione semicircolare, per cui non \u00e8 dato cogliere immediatamente il confine che separa la maggioranza di governo dall\u2019opposizione. Il che \u00e8 perfettamente corrispondente alla forma di governo parlamentare di tipo invece consensuale, dove l\u2019esistenza di un sistema multipartitico e multipolare, espressione delle fratture che attraversano una societ\u00e0 per questo eterogenea, permette agli elettori di votare solo per i partiti, i quali decidono poi in Parlamento se e come dar vita a (instabili) governi di coalizione, guidati da un Presidente del Consiglio che ha principalmente il compito di mediare tra i partiti che compongono la sua maggioranza parlamentare.<\/p>\n<p>Tale assetto ha caratterizzato il funzionamento della nostra forma di governo parlamentare fino al 1994, quando, com\u2019\u00e8 noto, si \u00e8 cercato di passare ad un sistema di tipo maggioritario grazie alla bipolarizzazione del sistema partitico indotta dalla modifica della legge elettorale. Tale sistema, che si prefiggeva governi di legislatura, in realt\u00e0 non ha mai funzionato, se si eccettua il Berlusconi III (2001-2005), perch\u00e9 le maggioranze di governo scaturite dalle urne sono presto o tardi entrate in crisi (Berlusconi I 1994, Prodi I 1998, Berlusconi III 2005, Prodi II 2008, Berlusconi IV 2011). L\u2019ingresso del M5S ha poi trasformato il nostro sistema partitico in tripolare, facendo cos\u00ec venire meno la precondizione per una designazione elettorale delle maggioranze di governo. Da qui le diverse maggioranze e i diversi Presidenti del Consiglio succedutisi nelle ultime due legislature (Letta, Renzi, Gentiloni, Conte I, Conte II, Draghi).<\/p>\n<p>In questo scenario politico-istituzionale \u00e8 evidente che il quadro politico, a distanza di ben trent\u2019anni dalla fine della c.d. Prima Repubblica, sia ancora ben lungi dall\u2019assestarsi e sottoposto a continue fibrillazioni: come dimostra il fenomeno tutto italiano del trasformismo parlamentare, cio\u00e8 di quegli eletti che, specie in occasione delle crisi di governo, cambiano gruppo parlamentare e, talora collocazione politica, rispetto a quella originaria, magari dando vita in corso di legislatura a \u201cpartiti di eletti\u201d la cui consistenza parlamentare si \u00e8 sempre finora rivelata maggiore rispetto all\u2019effettivo seguito elettorale, come dimostrano i <em>flop <\/em>elettorali di <em>Futuro e Libert\u00e0<\/em> di Fini, del <em>Nuovo Centro destra<\/em> di Alfano ed oggi di <em>Insieme per il Futuro<\/em> di Di Maio e di <em>Coraggio Italia<\/em> di Toti e Brugnaro (e chiss\u00e0 quale sarebbe stato il risultato elettorale di <em>Italia Viva <\/em>di Renzi se non si fosse alleata con<em> Azione <\/em>di Calenda). Veniamo dunque da una legislatura in cui tale fenomeno \u00e8 esploso, con ben 198 cambi di gruppo al Senato e 401 alla Camera, dove il gruppo misto \u00e8 divenuto il secondo per consistenza numerica (v. le tabelle da me curate in questo blog alla sezione <a href=\"https:\/\/www.lacostituzione.info\/index.php\/2019\/10\/14\/banca-dati-sulla-mobilita-parlamentare\/\" class=\"broken_link\"><em>Gruppi in movimento<\/em><\/a>).<\/p>\n<p>Dicevamo all\u2019inizio della conformazione architettonica delle camere. Quello che potrebbe sembrare un elemento tutto sommato esteriore invece non \u00e8 affatto irrilevante anche ai fini del funzionamento del nostro sistema di governo. Basterebbe ad esempio notare che le proposte favorevoli ad un ampliamento delle competenze del Parlamento in seduta comune (a cominciare dal conferimento e dalla revoca della fiducia al governo per finire alla conversione dei decreti legge) si sono potute formulare in questi ultimi mesi perch\u00e9 solo ora, dopo la riduzione del numero dei parlamentari da 945 a 600, l\u2019aula di Montecitorio potrebbe contenerli tutti, mentre prima non era possibile (ed infatti le camere riunite si riuniscono non per discutere ma per eleggere).<\/p>\n<p>Proprio la riduzione del numero dei parlamentari potrebbe indurre ad una semplice innovazione, a mio modesto avviso solo apparentemente marginale, ma forse invece non totalmente inutile, e comunque di grande impatto, quantomeno visivo. Anzich\u00e9, come detto, \u201crestringere\u201d i due emicicli &#8211; il che, peraltro costringerebbe le forze politiche di destra e di sinistra ad una innaturale convergenza verso il centro, abbandonano le tradizionali postazioni \u2013 si potrebbe invece profittare di tale riduzione per lasciare tra maggioranza di governo ed opposizione un settore dell\u2019emiciclo vuoto per marcare, anche visivamente, la distanza tra le due, esattamente come avviene in Gran Bretagna?<\/p>\n<p>Lungi da me ovviamente l\u2019idea che in tal modo si possa limitare il transfughismo parlamentare, che ha profonde radici nella nostra cultura politico-parlamentare. Per\u00f2 credo che si farebbe quantomeno un servizio agli elettori in termini di trasparenza e di responsabilit\u00e0 se costoro potessero immediatamente identificare chi sta con il governo e chi invece \u00e8 chiamato a fare opposizione.<\/p>\n<p>Sarebbe una piccola, modesta innovazione, certo, ma dal grande significato.\u00a0\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>di\u00a0Salvatore Curreri Il Corriere della Sera d\u00e0 oggi conto, con tanto di foto, degli interventi strutturali che Camera e Senato stanno apportando alle file degli scranni a seguito della riduzione del numero dei rispettivi componenti (com\u2019\u00e8 noto da 630 a 400 deputati e da 315 a 200 senatori elettivi).<\/p>\n<div class='heateorSssClear'><\/div><div  class='heateor_sss_sharing_container heateor_sss_horizontal_sharing' data-heateor-sss-href='https:\/\/www.lacostituzione.info\/index.php\/2022\/10\/06\/la-nuova-disposizione-dei-seggi-una-questione-non-marginale-e-una-modesta-proposta\/'><div class='heateor_sss_sharing_title' style=\"font-weight:bold\" >Condividi!<\/div><div class=\"heateor_sss_sharing_ul\"><a aria-label=\"Facebook\" class=\"heateor_sss_facebook\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2022%2F10%2F06%2Fla-nuova-disposizione-dei-seggi-una-questione-non-marginale-e-una-modesta-proposta%2F\" title=\"Facebook\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#0765FE;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path fill=\"#fff\" d=\"M28 16c0-6.627-5.373-12-12-12S4 9.373 4 16c0 5.628 3.875 10.35 9.101 11.647v-7.98h-2.474V16H13.1v-1.58c0-4.085 1.849-5.978 5.859-5.978.76 0 2.072.15 2.608.298v3.325c-.283-.03-.775-.045-1.386-.045-1.967 0-2.728.745-2.728 2.683V16h3.92l-.673 3.667h-3.247v8.245C23.395 27.195 28 22.135 28 16Z\"><\/path><\/svg><\/span><\/a><a aria-label=\"Twitter\" class=\"heateor_sss_button_twitter\" href=\"https:\/\/twitter.com\/intent\/tweet?text=La%20nuova%20disposizione%20dei%20seggi%3A%20una%20questione%20non%20marginale%20%28e%20una%20modesta%20proposta%29&url=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2022%2F10%2F06%2Fla-nuova-disposizione-dei-seggi-una-questione-non-marginale-e-una-modesta-proposta%2F\" title=\"Twitter\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_twitter\" style=\"background-color:#55acee;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 39 39\"><path d=\"M28 8.557a9.913 9.913 0 0 1-2.828.775 4.93 4.93 0 0 0 2.166-2.725 9.738 9.738 0 0 1-3.13 1.194 4.92 4.92 0 0 0-3.593-1.55 4.924 4.924 0 0 0-4.794 6.049c-4.09-.21-7.72-2.17-10.15-5.15a4.942 4.942 0 0 0-.665 2.477c0 1.71.87 3.214 2.19 4.1a4.968 4.968 0 0 1-2.23-.616v.06c0 2.39 1.7 4.38 3.952 4.83-.414.115-.85.174-1.297.174-.318 0-.626-.03-.928-.086a4.935 4.935 0 0 0 4.6 3.42 9.893 9.893 0 0 1-6.114 2.107c-.398 0-.79-.023-1.175-.068a13.953 13.953 0 0 0 7.55 2.213c9.056 0 14.01-7.507 14.01-14.013 0-.213-.005-.426-.015-.637.96-.695 1.795-1.56 2.455-2.55z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a aria-label=\"Reddit\" class=\"heateor_sss_button_reddit\" href=\"https:\/\/reddit.com\/submit?url=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2022%2F10%2F06%2Fla-nuova-disposizione-dei-seggi-una-questione-non-marginale-e-una-modesta-proposta%2F&title=La%20nuova%20disposizione%20dei%20seggi%3A%20una%20questione%20non%20marginale%20%28e%20una%20modesta%20proposta%29\" title=\"Reddit\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_reddit\" style=\"background-color:#ff5700;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-3.5 -3.5 39 39\"><path d=\"M28.543 15.774a2.953 2.953 0 0 0-2.951-2.949 2.882 2.882 0 0 0-1.9.713 14.075 14.075 0 0 0-6.85-2.044l1.38-4.349 3.768.884a2.452 2.452 0 1 0 .24-1.176l-4.274-1a.6.6 0 0 0-.709.4l-1.659 5.224a14.314 14.314 0 0 0-7.316 2.029 2.908 2.908 0 0 0-1.872-.681 2.942 2.942 0 0 0-1.618 5.4 5.109 5.109 0 0 0-.062.765c0 4.158 5.037 7.541 11.229 7.541s11.22-3.383 11.22-7.541a5.2 5.2 0 0 0-.053-.706 2.963 2.963 0 0 0 1.427-2.51zm-18.008 1.88a1.753 1.753 0 0 1 1.73-1.74 1.73 1.73 0 0 1 1.709 1.74 1.709 1.709 0 0 1-1.709 1.711 1.733 1.733 0 0 1-1.73-1.711zm9.565 4.968a5.573 5.573 0 0 1-4.081 1.272h-.032a5.576 5.576 0 0 1-4.087-1.272.6.6 0 0 1 .844-.854 4.5 4.5 0 0 0 3.238.927h.032a4.5 4.5 0 0 0 3.237-.927.6.6 0 1 1 .844.854zm-.331-3.256a1.726 1.726 0 1 1 1.709-1.712 1.717 1.717 0 0 1-1.712 1.712z\" fill=\"#fff\"\/><\/svg><\/span><\/a><a aria-label=\"Linkedin\" class=\"heateor_sss_button_linkedin\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2022%2F10%2F06%2Fla-nuova-disposizione-dei-seggi-una-questione-non-marginale-e-una-modesta-proposta%2F\" title=\"Linkedin\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_linkedin\" style=\"background-color:#0077b5;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path d=\"M6.227 12.61h4.19v13.48h-4.19V12.61zm2.095-6.7a2.43 2.43 0 0 1 0 4.86c-1.344 0-2.428-1.09-2.428-2.43s1.084-2.43 2.428-2.43m4.72 6.7h4.02v1.84h.058c.56-1.058 1.927-2.176 3.965-2.176 4.238 0 5.02 2.792 5.02 6.42v7.395h-4.183v-6.56c0-1.564-.03-3.574-2.178-3.574-2.18 0-2.514 1.7-2.514 3.46v6.668h-4.187V12.61z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a aria-label=\"Pinterest\" class=\"heateor_sss_button_pinterest\" href=\"https:\/\/www.lacostituzione.info\/index.php\/2022\/10\/06\/la-nuova-disposizione-dei-seggi-una-questione-non-marginale-e-una-modesta-proposta\/\" onclick=\"event.preventDefault();javascript:void( (function() {var e=document.createElement('script' );e.setAttribute('type','text\/javascript' );e.setAttribute('charset','UTF-8' );e.setAttribute('src','\/\/assets.pinterest.com\/js\/pinmarklet.js?r='+Math.random()*99999999);document.body.appendChild(e)})());\" title=\"Pinterest\" rel=\"noopener\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_pinterest\" style=\"background-color:#cc2329;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-2 -2 35 35\"><path fill=\"#fff\" d=\"M16.539 4.5c-6.277 0-9.442 4.5-9.442 8.253 0 2.272.86 4.293 2.705 5.046.303.125.574.005.662-.33.061-.231.205-.816.27-1.06.088-.331.053-.447-.191-.736-.532-.627-.873-1.439-.873-2.591 0-3.338 2.498-6.327 6.505-6.327 3.548 0 5.497 2.168 5.497 5.062 0 3.81-1.686 7.025-4.188 7.025-1.382 0-2.416-1.142-2.085-2.545.397-1.674 1.166-3.48 1.166-4.689 0-1.081-.581-1.983-1.782-1.983-1.413 0-2.548 1.462-2.548 3.419 0 1.247.421 2.091.421 2.091l-1.699 7.199c-.505 2.137-.076 4.755-.039 5.019.021.158.223.196.314.077.13-.17 1.813-2.247 2.384-4.324.162-.587.929-3.631.929-3.631.46.876 1.801 1.646 3.227 1.646 4.247 0 7.128-3.871 7.128-9.053.003-3.918-3.317-7.568-8.361-7.568z\"\/><\/svg><\/span><\/a><a aria-label=\"Whatsapp\" class=\"heateor_sss_whatsapp\" href=\"https:\/\/api.whatsapp.com\/send?text=La%20nuova%20disposizione%20dei%20seggi%3A%20una%20questione%20non%20marginale%20%28e%20una%20modesta%20proposta%29%20https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2022%2F10%2F06%2Fla-nuova-disposizione-dei-seggi-una-questione-non-marginale-e-una-modesta-proposta%2F\" title=\"Whatsapp\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#55eb4c;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-6 -5 40 40\"><path class=\"heateor_sss_svg_stroke heateor_sss_no_fill\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\" d=\"M 11.579798566743314 24.396926207859085 A 10 10 0 1 0 6.808479557110079 20.73576436351046\"><\/path><path d=\"M 7 19 l -1 6 l 6 -1\" class=\"heateor_sss_no_fill heateor_sss_svg_stroke\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\"><\/path><path d=\"M 10 10 q -1 8 8 11 c 5 -1 0 -6 -1 -3 q -4 -3 -5 -5 c 4 -2 -1 -5 -1 -4\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><\/div><div class=\"heateorSssClear\"><\/div><\/div><div class='heateorSssClear'><\/div>","protected":false},"author":13,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"enabled":false},"version":2}},"categories":[5],"tags":[1637,1078,1097,113],"class_list":["post-8487","post","type-post","status-publish","format-standard","hentry","category-lavori-in-corso","tag-aule","tag-maggioranza-parlamentare","tag-minoranza","tag-parlamento"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p84sDq-2cT","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/posts\/8487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/comments?post=8487"}],"version-history":[{"count":0,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/posts\/8487\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/media?parent=8487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/categories?post=8487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/tags?post=8487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}