{"id":8924,"date":"2023-12-12T11:09:10","date_gmt":"2023-12-12T10:09:10","guid":{"rendered":"http:\/\/www.lacostituzione.info\/?p=8924"},"modified":"2023-12-12T11:09:12","modified_gmt":"2023-12-12T10:09:12","slug":"8924","status":"publish","type":"post","link":"https:\/\/www.lacostituzione.info\/index.php\/2023\/12\/12\/8924\/","title":{"rendered":""},"content":{"rendered":"\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.lacostituzione.info\/wp-content\/uploads\/2023\/12\/cons-st.jpeg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8925\" data-permalink=\"https:\/\/www.lacostituzione.info\/index.php\/2023\/12\/12\/8924\/cons-st\/#main\" data-orig-file=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2023\/12\/cons-st.jpeg\" data-orig-size=\"275,183\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"cons st\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2023\/12\/cons-st.jpeg\" data-large-file=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2023\/12\/cons-st.jpeg\" class=\"aligncenter size-thumbnail wp-image-8925\" src=\"http:\/\/www.lacostituzione.info\/wp-content\/uploads\/2023\/12\/cons-st-150x150.jpeg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>di <strong>Glauco Nori<\/strong><\/p>\n<p>La Corte di Giustizia CE esclude di poter intervenire sugli atti della Commissione quando questa dispone di un&#8217;ampia libert\u00e0 di valutazione: deve limitarsi a verificare se non sia incors<strong>a <\/strong>in errore manifesto o in sviamento di potere. L&#8217;errore \u00e8 considerato manifesto quando \u00e8 desumibile dal provvedimento impugnato, senza bisogno di una istruttoria apposita. La discrezionalit\u00e0 \u00e8 stata ritenuta non soggetta a verifica da parte del giudice.<!--more-->L&#8217;orientamento della giurisprudenza italiana \u00e8 diverso. Senza richiamarne la motivazione, ci si limiter\u00e0 a qualche osservazione.<\/p>\n<p>Nel settore dei servizi, con gli strumenti oggi disponibili, i tempi si sono ridotti in misura non prevedibile fino a poco fa, mentre i tempi della giustizia, anche di quella amministrativa, non si pu\u00f2 dire che si siano abbreviati. Se sorge un problema di giustizia, ci vuole un tempo non breve per la soluzione anche quando la rapidit\u00e0 sarebbe decisiva. L&#8217;impugnativa di un provvedimento amministrativo, in caso di sospensione dell&#8217;esecutoriet\u00e0, pu\u00f2 portare alla sua attuazione, se riconosciuto legittimo, quando le condizioni sono mutate oppure, se la sospensione non c&#8217;\u00e8 stata, all&#8217;annullamento di un atto illegittimo gi\u00e0 parzialmente eseguito.<\/p>\n<p>Si sono richiamati i servizi, ma gli inconvenienti possono investire anche altri settori, in particolare i lavori pubblici. Disposta la sospensione del provvedimento impugnato, a sentenza intervenuta \u00e8 capitato che si sia dovuto rivedere il progetto non foss&#8217;altro per i costi, aumentati nel frattempo, cos\u00ec da richiedere un aggiornamento della copertura finanziaria. Di conseguenza,\u00a0 pi\u00f9 ampia \u00e8 la sfera di indagine del <strong>\u00a0<\/strong>giudice, maggiori sono i rischi.<\/p>\n<p>I principi di diritto nel tempo non sono mutati; sono alcune condizioni di ordine economico e sociale a non essere pi\u00f9 le stesse.<\/p>\n<p>Tempo a dietro qualcuno fece presente che, attraverso un controllo sulla motivazione, talvolta il Giudice finiva con l&#8217;interferire con la discrezionalit\u00e0. Si prospettava, pertanto, l&#8217;opportunit\u00e0 di domandarsi se qualche limite non fosse\u00a0 necessario.\u00a0Secondo l&#8217;art.113 della Costituzione \u00e8 &#8220;sempre&#8221; ammessa la tutela giurisdizionale degli interessi legittimi. I criteri per individuarli nella Costituzione non sono indicati e non sono facilmente\u00a0 desumibili nemmeno dalla discussione in Assemblea Costituente, interessata soprattutto alla regolazione del potere di annullamento degli atti dell&#8217;Amministrazione. La discussione, in pratica, si \u00e8 svolta sul presupposto della nozione di interesse legittimo dell&#8217;epoca.<\/p>\n<p>Sulla incompetenza e la violazione di legge, come era prevedibile, questioni di principio non potevano sorgere; non altrettanto sull&#8217;eccesso di potere, data l&#8217;elasticit\u00e0 della figura la cui individuazione \u00e8 stata lasciata al giudice che doveva tutelarla.<\/p>\n<p>Non dovrebbe essere senza significato che il Giudice comunitario si sia limitato i poteri di intervento in questo ambito. Si potr\u00e0 osservare che i due ordinamenti, quello comunitario e quello statale, hanno funzioni diverse cos\u00ec da richiedere prudenza nel trovare collegamenti.\u00a0 Senonch\u00e9 sembra che l&#8217;orientamento della Corte di Giustizia non sia fondato sui caratteri dell&#8217;ordinamento comunitario, ma sul rapporto tra discrezionalit\u00e0 e giurisdizione, nel senso che un controllo sull&#8217;esercizio della discrezionalit\u00e0 sarebbe incompatibile con la giurisdizione.<\/p>\n<p>In questi ultimi venti anni i nuovi mezzi\u00a0 di comunicazione hanno cambiato radicalmente la situazione, sopratutto nei settori economici e finanziari.\u00a0<\/p>\n<p>I nuovi strumenti richiederebbero\u00a0 interventi, se non rapidi, almeno ridotti rispetto agli attuali, sufficienti per\u00a0 valutare tutte le condizioni di fatto con criteri anche di opportunit\u00e0, oltre che formali. Anche gli organi operativi vengono a trovarsi in difficolt\u00e0. Un giudice potrebbe non essere il soggetto pi\u00f9 adatto al controllo\u00a0 dal momento che deve seguire i criteri generali, fissati dalla norma in forma astratta, per procedere a giudizi sulla prevalenza di interessi, tra di loro non sempre\u00a0 compatibili. C&#8217;\u00e8 da domandarsi se sia ancora il caso di mantenere controlli giurisdizionali fondati su principi elastici, o di attenersi alle valutazioni di opportunit\u00e0 dell&#8217;organo competente, con risultati economici spesso migliori.<\/p>\n<p>Vale la pena di ripeterlo: in caso di ricorso, il Giudice pu\u00f2 disporre la sospensiva, qualunque sia il motivo fatto valere. In caso di operazioni di peso finanziario notevole, dopo la sentenza ci si pu\u00f2 trovare nella necessit\u00e0 di rinegoziarne le condizioni, sacrificando altre operazioni o aumentando il debito. Di conseguenza\u00a0 pi\u00f9 ampia \u00e8 la sfera di intervento del Giudice, &#8211; sembra il caso di sottolinearlo &#8211; maggiore diventa il rischio di effetti pregiudizievoli. In altre parole, \u00e8 ancora preferibile, in alcuni settori, consentire la sospensiva, con l&#8217;esecuzione dell&#8217;opera a costi maggiori, rispetto alla eventualit\u00e0 che l&#8217;opera non sia eseguita da chi ne avrebbe avuto il diritto, ma con la possibilit\u00e0 di essere risarcito del danno? In questo caso l&#8217;onere complessivo per il committente sarebbe presumibilmente inferiore, tenuto conto che il costo minore dell&#8217;opera compenserebbe il risarcimento in favore dell&#8217;impresa danneggiata.<\/p>\n<p>Andrebbero, naturalmente, rivisti alcuni principi.\u00a0Per cominciare, che significa oggi &#8220;discrezionalit\u00e0&#8221;?<\/p>\n<p>A suo tempo se ne \u00e8 discusso\u00a0 anche per la sua inerenza alla &#8220;funzione&#8221;. Oggi l&#8217;esame dovrebbe essere aggiornato, data la diversit\u00e0 delle condizioni.<\/p>\n<p>Certi principi si sono formati quando giudice amministrativo era il solo Consiglio di Stato, i cui tempi per la definizione delle controversie erano proporzionati a quelli dei rapporti giuridici coinvolti. Forse anche per questo \u00e8 stato consentito al Giudice di intervenire su alcuni aspetti\u00a0 dell&#8217;attivit\u00e0 amministrativa soggetti ad una disciplina elastica.\u00a0 All&#8217;organo competente era rimessa la individuazione degli interessi rilevanti e la loro comparazione ponderale. Si \u00e8 ritenuto, come conseguenza, che per la verifica della legittimit\u00e0 dell&#8217;azione amministrativa il controllo del Giudice intervenisse sulla individuazione degli interessi rilevanti, sui criteri per la loro valutazione e per la messa a confronto.<\/p>\n<p>Non \u00e8 stato colto, o non \u00e8 stato considerato rilevante, che in questo modo si consentiva al giudice di inserirsi nella sfera della discrezionalit\u00e0 che, per essere fondata sulla valutazione complessiva degli interessi, in linea di principio sarebbe dovuta appartenere solo al soggetto operante che con\u00a0 quegli interessi entrava in contatto. Non sono mancati casi in cui, per la difficolt\u00e0 di definirne la sfera, il giudice ha finito per fissare direttamente i criteri per l&#8217;esercizio corretto delle valutazioni, pur trovandosi nella posizione non adatta.<\/p>\n<p>Come si \u00e8 gi\u00e0 rilevato, il giudice \u00e8 chiamato a giudicare sui criteri, secondo i quali il potere viene esercitato, sotto i profili fatti valere col ricorso, staccati dagli altri, applicati nel provvedimento con una visione complessiva e coordinata. Si arriva\u00a0 cos\u00ec ad un giudizio che pu\u00f2 finire con l&#8217;essere condotto con\u00a0 criteri non coincidenti con quelli che il soggetto competente si era trovato a seguire. Di questo probabilmente ha tenuto conto il Giudice comunitario collegando il problema, pi\u00f9 che al rapporto tra ordinamenti, a quello tra giurisdizione e discrezionalit\u00e0.<\/p>\n<p>Non \u00e8 prevedibile che la figura dell&#8217;interesse legittimo possa essere ridimensionata dallo stesso Giudice che a suo tempo l&#8217;ha definita.<\/p>\n<p>La questione potrebbe essere sottoposta alla Corte costituzionale per accertare se la forma attuale di tutela sia ancora compatibile con la collocazione nuova\u00a0 che hanno assunto gli interessi per la rapidit\u00e0 della loro evoluzione.<\/p>\n<p>Sono restati investiti dallo stesso problema anche rapporti, definibili come tradizionali, soggetti ad una disciplina radicata da tempo.<\/p>\n<p>Le c.d. concessioni balneari ne sono un esempio. Negli ultimi decenni il loro rilievo economico\u00a0 \u00e8 aumentato notevolmente. In sede di rinnovo sono sorte questioni\u00a0 in termini che non \u00e8 il caso di ricordare perch\u00e8 ormai ben noti.<\/p>\n<p>In discussione \u00e8 l&#8217;applicabilit\u00e0 della Direttiva Bolkestein. Su di un punto non si dovrebbero avere dubbi, che la sua applicabilit\u00e0 alle concessioni balneari deve essere accertata dalla Corte di Giustizia. Anche se la Direttiva non fosse ritenuta applicabile, le conclusioni non dovrebbero essere diverse.<\/p>\n<p>I beni del demanio possono essere utilizzati ai fini pubblici, a cui sono destinati, con la collaborazione dei privati attraverso una concessione. Nella scelta del privato dovrebbe essere rispettato il principio di uguaglianza dal momento che il concessionario si trova ad operare in un mercato nel quale principio fondamentale \u00e8 la parit\u00e0 della posizione degli interessati.\u00a0 Anche secondo la stessa normativa italiana, indipendetemente da quella comunitaria, sarebbe necessaria la gara tra gli interessati (tanto pi\u00f9 quando al concessionario viene richiesto un corrispettivo particolarmente favorevole).\u00a0 Chi sostiene il contrario sino ad oggi non ha indicato la norma o il principio in base al quale le concessioni andrebbero rinnovate senza gara, lasciando cos\u00ec all&#8217;amministrazione concedente la scelta del concessionario e la determinazione del corrispettivo. Si \u00e8 fatto valere che gran parte degli investimenti, fatti nel tempo, non sono stati ancora ammortizzati, senza tenere conto che, per questa parte, il precedente concessionario andrebbe indennizzato (in proposito c&#8217;\u00e8 stato chi \u00e8 andato a verificare che gli impianti sono stati aggiornati con una rapidit\u00e0 non consueta).<\/p>\n<p>La soluzione potrebbe essere trovata anche in tempi pi\u00f9 brevi di quella comunitaria. Se qualcuno, che ha fatto offerta pi\u00f9 favorevole, impugnasse il rinnovo della concessione al concessionario precedente, la questione potrebbe essere portata alla Corte costituzionale sul cui orientamento non sembra che potrebbero esserci dubbi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>di Glauco Nori La Corte di Giustizia CE esclude di poter intervenire sugli atti della Commissione quando questa dispone di un&#8217;ampia libert\u00e0 di valutazione: deve limitarsi a verificare se non sia incorsa in errore manifesto o in sviamento di potere. L&#8217;errore \u00e8 considerato manifesto quando \u00e8 desumibile dal provvedimento impugnato, senza bisogno di una istruttoria &#8230; <a title=\"\" class=\"read-more\" href=\"https:\/\/www.lacostituzione.info\/index.php\/2023\/12\/12\/8924\/\">Leggi tutto<\/a><\/p>\n<div class='heateorSssClear'><\/div><div  class='heateor_sss_sharing_container heateor_sss_horizontal_sharing' data-heateor-sss-href='https:\/\/www.lacostituzione.info\/index.php\/2023\/12\/12\/8924\/'><div class='heateor_sss_sharing_title' style=\"font-weight:bold\" >Condividi!<\/div><div class=\"heateor_sss_sharing_ul\"><a aria-label=\"Facebook\" class=\"heateor_sss_facebook\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2023%2F12%2F12%2F8924%2F\" title=\"Facebook\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#0765FE;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path fill=\"#fff\" d=\"M28 16c0-6.627-5.373-12-12-12S4 9.373 4 16c0 5.628 3.875 10.35 9.101 11.647v-7.98h-2.474V16H13.1v-1.58c0-4.085 1.849-5.978 5.859-5.978.76 0 2.072.15 2.608.298v3.325c-.283-.03-.775-.045-1.386-.045-1.967 0-2.728.745-2.728 2.683V16h3.92l-.673 3.667h-3.247v8.245C23.395 27.195 28 22.135 28 16Z\"><\/path><\/svg><\/span><\/a><a aria-label=\"Twitter\" class=\"heateor_sss_button_twitter\" href=\"https:\/\/twitter.com\/intent\/tweet?text=&url=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2023%2F12%2F12%2F8924%2F\" title=\"Twitter\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_twitter\" style=\"background-color:#55acee;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 39 39\"><path d=\"M28 8.557a9.913 9.913 0 0 1-2.828.775 4.93 4.93 0 0 0 2.166-2.725 9.738 9.738 0 0 1-3.13 1.194 4.92 4.92 0 0 0-3.593-1.55 4.924 4.924 0 0 0-4.794 6.049c-4.09-.21-7.72-2.17-10.15-5.15a4.942 4.942 0 0 0-.665 2.477c0 1.71.87 3.214 2.19 4.1a4.968 4.968 0 0 1-2.23-.616v.06c0 2.39 1.7 4.38 3.952 4.83-.414.115-.85.174-1.297.174-.318 0-.626-.03-.928-.086a4.935 4.935 0 0 0 4.6 3.42 9.893 9.893 0 0 1-6.114 2.107c-.398 0-.79-.023-1.175-.068a13.953 13.953 0 0 0 7.55 2.213c9.056 0 14.01-7.507 14.01-14.013 0-.213-.005-.426-.015-.637.96-.695 1.795-1.56 2.455-2.55z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a aria-label=\"Reddit\" class=\"heateor_sss_button_reddit\" href=\"https:\/\/reddit.com\/submit?url=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2023%2F12%2F12%2F8924%2F&title=\" title=\"Reddit\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_reddit\" style=\"background-color:#ff5700;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-3.5 -3.5 39 39\"><path d=\"M28.543 15.774a2.953 2.953 0 0 0-2.951-2.949 2.882 2.882 0 0 0-1.9.713 14.075 14.075 0 0 0-6.85-2.044l1.38-4.349 3.768.884a2.452 2.452 0 1 0 .24-1.176l-4.274-1a.6.6 0 0 0-.709.4l-1.659 5.224a14.314 14.314 0 0 0-7.316 2.029 2.908 2.908 0 0 0-1.872-.681 2.942 2.942 0 0 0-1.618 5.4 5.109 5.109 0 0 0-.062.765c0 4.158 5.037 7.541 11.229 7.541s11.22-3.383 11.22-7.541a5.2 5.2 0 0 0-.053-.706 2.963 2.963 0 0 0 1.427-2.51zm-18.008 1.88a1.753 1.753 0 0 1 1.73-1.74 1.73 1.73 0 0 1 1.709 1.74 1.709 1.709 0 0 1-1.709 1.711 1.733 1.733 0 0 1-1.73-1.711zm9.565 4.968a5.573 5.573 0 0 1-4.081 1.272h-.032a5.576 5.576 0 0 1-4.087-1.272.6.6 0 0 1 .844-.854 4.5 4.5 0 0 0 3.238.927h.032a4.5 4.5 0 0 0 3.237-.927.6.6 0 1 1 .844.854zm-.331-3.256a1.726 1.726 0 1 1 1.709-1.712 1.717 1.717 0 0 1-1.712 1.712z\" fill=\"#fff\"\/><\/svg><\/span><\/a><a aria-label=\"Linkedin\" class=\"heateor_sss_button_linkedin\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2023%2F12%2F12%2F8924%2F\" title=\"Linkedin\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_linkedin\" style=\"background-color:#0077b5;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path d=\"M6.227 12.61h4.19v13.48h-4.19V12.61zm2.095-6.7a2.43 2.43 0 0 1 0 4.86c-1.344 0-2.428-1.09-2.428-2.43s1.084-2.43 2.428-2.43m4.72 6.7h4.02v1.84h.058c.56-1.058 1.927-2.176 3.965-2.176 4.238 0 5.02 2.792 5.02 6.42v7.395h-4.183v-6.56c0-1.564-.03-3.574-2.178-3.574-2.18 0-2.514 1.7-2.514 3.46v6.668h-4.187V12.61z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a aria-label=\"Pinterest\" class=\"heateor_sss_button_pinterest\" href=\"https:\/\/www.lacostituzione.info\/index.php\/2023\/12\/12\/8924\/\" onclick=\"event.preventDefault();javascript:void( (function() {var e=document.createElement('script' );e.setAttribute('type','text\/javascript' );e.setAttribute('charset','UTF-8' );e.setAttribute('src','\/\/assets.pinterest.com\/js\/pinmarklet.js?r='+Math.random()*99999999);document.body.appendChild(e)})());\" title=\"Pinterest\" rel=\"noopener\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_pinterest\" style=\"background-color:#cc2329;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-2 -2 35 35\"><path fill=\"#fff\" d=\"M16.539 4.5c-6.277 0-9.442 4.5-9.442 8.253 0 2.272.86 4.293 2.705 5.046.303.125.574.005.662-.33.061-.231.205-.816.27-1.06.088-.331.053-.447-.191-.736-.532-.627-.873-1.439-.873-2.591 0-3.338 2.498-6.327 6.505-6.327 3.548 0 5.497 2.168 5.497 5.062 0 3.81-1.686 7.025-4.188 7.025-1.382 0-2.416-1.142-2.085-2.545.397-1.674 1.166-3.48 1.166-4.689 0-1.081-.581-1.983-1.782-1.983-1.413 0-2.548 1.462-2.548 3.419 0 1.247.421 2.091.421 2.091l-1.699 7.199c-.505 2.137-.076 4.755-.039 5.019.021.158.223.196.314.077.13-.17 1.813-2.247 2.384-4.324.162-.587.929-3.631.929-3.631.46.876 1.801 1.646 3.227 1.646 4.247 0 7.128-3.871 7.128-9.053.003-3.918-3.317-7.568-8.361-7.568z\"\/><\/svg><\/span><\/a><a aria-label=\"Whatsapp\" class=\"heateor_sss_whatsapp\" href=\"https:\/\/api.whatsapp.com\/send?text=%20https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2023%2F12%2F12%2F8924%2F\" title=\"Whatsapp\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#55eb4c;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-6 -5 40 40\"><path class=\"heateor_sss_svg_stroke heateor_sss_no_fill\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\" d=\"M 11.579798566743314 24.396926207859085 A 10 10 0 1 0 6.808479557110079 20.73576436351046\"><\/path><path d=\"M 7 19 l -1 6 l 6 -1\" class=\"heateor_sss_no_fill heateor_sss_svg_stroke\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\"><\/path><path d=\"M 10 10 q -1 8 8 11 c 5 -1 0 -6 -1 -3 q -4 -3 -5 -5 c 4 -2 -1 -5 -1 -4\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><\/div><div class=\"heateorSssClear\"><\/div><\/div><div class='heateorSssClear'><\/div>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"enabled":false},"version":2}},"categories":[12],"tags":[119,1688,1687,1432],"class_list":["post-8924","post","type-post","status-publish","format-standard","hentry","category-editoriale","tag-consiglio-di-stato","tag-discrezionalita-amministrativa","tag-giudice-amministrativo","tag-opere-pubbliche"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/s84sDq-8924","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/posts\/8924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/comments?post=8924"}],"version-history":[{"count":0,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/posts\/8924\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/media?parent=8924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/categories?post=8924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/tags?post=8924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}