{"id":9327,"date":"2024-11-12T10:57:32","date_gmt":"2024-11-12T09:57:32","guid":{"rendered":"http:\/\/www.lacostituzione.info\/?p=9327"},"modified":"2024-11-12T10:57:45","modified_gmt":"2024-11-12T09:57:45","slug":"a-proposito-del-possibile-ruolo-delle-procure-a-seguito-di-uneventuale-separazione-delle-carriere-giudiziarie","status":"publish","type":"post","link":"https:\/\/www.lacostituzione.info\/index.php\/2024\/11\/12\/a-proposito-del-possibile-ruolo-delle-procure-a-seguito-di-uneventuale-separazione-delle-carriere-giudiziarie\/","title":{"rendered":"A proposito del possibile ruolo delle procure a seguito di un\u2019eventuale separazione delle carriere giudiziarie"},"content":{"rendered":"<p>di <strong>Sergio Bartole*<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9328\" data-permalink=\"https:\/\/www.lacostituzione.info\/index.php\/2024\/11\/12\/a-proposito-del-possibile-ruolo-delle-procure-a-seguito-di-uneventuale-separazione-delle-carriere-giudiziarie\/procurat\/#main\" data-orig-file=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2024\/11\/procurat.jpg\" data-orig-size=\"800,450\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"procurat\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2024\/11\/procurat-300x169.jpg\" data-large-file=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2024\/11\/procurat.jpg\" class=\"alignright size-thumbnail wp-image-9328\" src=\"http:\/\/www.lacostituzione.info\/wp-content\/uploads\/2024\/11\/procurat-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/strong><\/p>\n<p>La forma di governo della Repubblica italiana \u00e8 pluralista, non solo in quanto recepisce e proietta a livello di poteri il pluralismo della nostra comunit\u00e0 nazionale, ma anche perch\u00e9 \u00e8 composta di un complesso di istituzioni fra loro separate e destinate a coordinarsi attraverso la collaborazione nonch\u00e9 il bilanciamento delle rispettive attribuzioni e orientamenti. Con l\u2019eventuale accoglimento della proposta separazione delle carriere di magistrati giudicanti e requirenti il numero di quelle istituzioni aumenterebbe con la divisione di un solo ordine di magistrati in due ordini distinti \u2013 appunto, uno dei giudicanti ed uno dei requirenti \u2013 governato ciascuno da un suo consiglio superiore. <!--more-->Gi\u00e0 Nicol\u00f2 Zanon ha censurato questa duplicazione di organi collegiali laddove meglio si sarebbe potuto fare dividendo in due sezioni l\u2019attuale Consiglio superiore. Il che avrebbe consentito di conservare l\u2019unicit\u00e0 della magistratura rendendo pi\u00f9 agevole la implementazione della garanzia della sua autonomia e indipendenza. Aldil\u00e0 delle vuote parole nel nuovo testo del primo comma dell\u2019art. 104 riformato, la soluzione attualmente proposta non solo duplica, con i rischi per la posizione costituzionale dei due ordini di magistrati, le responsabilit\u00e0 e i problemi connessi alla accennata garanzia, ma anche pone la questione del ruolo della nuova istituzione dell\u2019ordine dei magistrati requirenti e delle sue relazioni con gli altri poteri dello Stato.<\/p>\n<p>La relazione governativa al disegno di legge costituzionale definisce indirettamente le funzioni dei magistrati requirenti in vista della separazione delle loro carriere ragionando di una \u201cstruttura pi\u00f9 coerente con le regole fondamentali del processo penale\u201d, e quindi accenna ad una conformit\u00e0 a queste del nuovo assetto. Questo approccio lega evidentemente l\u2019auspicata riforma al ruolo che i procuratori sono chiamati a svolgere nel processo penale, e quindi indirizza ad una definizione di quel ruolo alla luce delle normative del codice di procedura penale, dunque in chiave infra-processuale. Ma a questa possibile definizione sfuggono le altre attivit\u00e0 delle procure, s\u00ec interne al loro ordine ma al tempo stesso potenzialmente suscettibili di un rilievo esterno in quanto toccano ambiti diversi sia per quanto ha tratto alle persone che per quanto attiene ai rapporti pubblici e privati interessati. Per cogliere una registrazione normativa di questi aspetti sembra allora naturale andare all\u2019art. 73 della martoriata legge sull\u2019ordinamento giudiziario, il cui testo non \u00e8 mai stato oggetto di una revisione integrale ma \u00e8 sempre stato rivisto a pezzi e bocconi. L\u2019elenco delle attribuzioni del pubblico ministero cui l\u2019articolo citato \u00e8 dedicato, si apre con l\u2019inizio e l\u2019esercizio dell\u2019azione penale, ma poi annovera la sorveglianza sull\u2019osservanza delle leggi e la pronta e regolare amministrazione della giustizia; la tutela dei diritti dello Stato, delle persone giuridiche e degli incapaci; la repressione dei reati e l\u2019applicazione delle misure di sicurezza; l\u2019esecuzione ed osservanza delle leggi d\u2019ordine pubblico e interessanti i diritti dello Stato.<\/p>\n<p>Si tratta di un plesso molto ampio di attribuzioni definite in termini molto vaghi e generici, per cui una loro pi\u00f9 concreta definizione \u00e8 rinviata al loro concreto esercizio. Ci\u00f2 vale in particolare per le attivit\u00e0 che non sfociano necessariamente in un percorso giudiziale quale quello che demanda ai giudici investiti dalle azioni penali promosse dalle procure l\u2019ultima parola sulla loro ammissibilit\u00e0. E\u2019 sulle attribuzioni meno puntualmente definite che conviene volgere l\u2019attenzione in quanto la loro enumerazione si presta ad interpretazioni molto elastiche che finiscono per essere sottoposte principalmente ai riscontri interni alla per nuovo separata e indipendente istituzione delle procure e sfuggono quindi ad un riesame giudiziale (si tratta di un testo che agevolmente potrebbe essere utilizzato per saggiare le considerazioni svolte da G. Pino nel capitolo sui problemi semantici e pragmatici del linguaggio giuridico nel volume <em>L\u2019interpretazione del diritto<\/em>, Torino 2021, 115 ss.).<\/p>\n<p>Per valutare questa prospettiva giova tenere presente che, a seguito dell\u2019eventuale approvazione del disegno di legge costituzionale di cui andiamo ragionando, verr\u00e0 appunto ad esistenza un ordine separato e indipendente delle procure cui in ultima istanza \u00e8 rimessa l\u2019individuazione del loro ruolo nel quadro del disegno complessivo dei poteri dello Stato e nei termini che i principi costituzionali lo consentano. Vi \u00e8 il rischio che, prendendo lo spunto da pratiche operative extra\u2013processuali dell\u2019istituzione o ordine delle procure, libere dal <em>restraint<\/em> della convivenza in un unico ordine con i magistrati giudicanti, esse siano guidate non da una finalit\u00e0 di giustizia come vorrebbe la pur conclamata loro appartenenza alla magistratura, ma da una sotterranea vocazione inquisitoria, la individuazione dei cui confini resti demandata alle procure medesime. Ci troveremmo di fronte all\u2019epifania di un potere anomalo la cui esistenza sconfesserebbe le logiche che guidano oggi il governo a proporre la separazione delle carriere giudiziarie ad evitare il supposto strapotere dei magistrati requirenti in riguardo degli organi giudicanti.<\/p>\n<p>Nonostante la presenza di passati interventi inquisitori che da taluno sono stati visti come vere e proprie rotture del principio di separazione dei poteri, non ci sono nella tradizione giuridica italiana elementi che lascino temere l\u2019avvento di un fenomeno del tipo di quello ora accennato. Non vi sono cio\u00e8 nella storia della Repubblica italiana precedenti comparabili a quel sistema delle prokurature che caratterizzava l\u2019Unione sovietica e gli Stati suoi satelliti. Quelle istituzioni avevano competenze che andavano oltre la persecuzione dei reati difronte alle autorit\u00e0 giurisdizionali e venivano sommariamente descritte come poteri generali di supervisione. Il che consentiva loro di monitorare gli atti prodotti dai livelli inferiori di governo, di investigare sulle illegittimit\u00e0 addebitabili a pubblici poteri e, infine, di scrutinare le stesse decisioni giudiziali anche nella fase preprocessuale e delle attivit\u00e0 penitenziarie. Seguendo le indicazioni della Raccomandazione del Comitato dei Ministri del Consiglio d\u2019Europa sul ruolo del Pubblico Ministero nell\u2019ordinamento penale (2000 \u2013 19), la Commissione europea per la democrazia attraverso il diritto, organo tecnico del Consiglio d\u2019Europa, meglio nota come Commissione di Venezia, ha ripetutamente censurato e bloccato i tentativi di alcuni Stati dell\u2019Europa orientale di riproporre in forme aggiornate le antiche Prokurature osservando che una ripresa delle antiche competenze \u201cconsiderably exceed the scope of functions performed by a prosecutor in a democratic, law abiding state\u201d (si vedano, per tutte, le opinioni della Commissione CDL-AD(2006)029, CDL-AD(2009)048 e CDL-AD(2017)028.<\/p>\n<p>Se il rischio degli indesiderabili sviluppi ora accennati dipende anche dalla generica ed equivoca definizione delle attribuzioni delle procure contenuta nell\u2019art. 73 ordinamento giudiziario, o forse meglio dalla mancata individuazione chiara e precisa di quelle attribuzioni nel progetto di legge costituzionale in discussione, converrebbe che il Parlamento si interroghi sul futuro dell\u2019ordine delle procure e sull\u2019eventuale necessit\u00e0 di emendare il testo oggi all\u2019esame fornendo elementi dettagliati per la definizione del ruolo delle procure nel sistema di governo, ad evitare di dare troppo spazio agli organi interessati nell\u2019individuazione dei loro compiti, semprech\u00e9 si intenda dare corso all\u2019iniziativa del Governo. L\u2019esposizione ai pericoli accennati pu\u00f2 portare ad esiti indesiderati. Ove le procure si atteggiassero in termini assimilabili al ruolo svolto nei Paesi dell\u2019Europa orientale dalle prokurature, qualcuno potrebbe porre il problema di evitare un loro strapotere e di predisporre un loro controllo esterno ovvero una loro dipendenza dal raccordo Governo \u2013 Parlamento con conseguente superamento dell\u2019autonomia ed indipendenza del loro ordine. Per porre riparo alle possibili degenerazioni del sistema potrebbe avverarsi, cio\u00e8, la previsione di quanti temono che la separazione delle carriere dei magistrati giudicanti e requirenti conduca passo dopo passo alla dipendenza delle procure dall\u2019esecutivo anzitutto o dal concorso di Governo e Parlamento.<\/p>\n<p>Il diritto comparato europeo conosce esempi di nomina parlamentare o ad opera del Capo dello Stato del vertice delle procure, di norma definito procuratore generale, con osservanza dei requisiti legislativi etici e professionali. Per quanto l\u2019adozione di sistemi siffatti sia accompagnata da garanzia istituzionali e personali degli uffici e dei loro titolari e \u201cshould be depoliticised\u201d (Commissione di Venezia CDL \u2013 AD(2017)028), va prendendo sempre pi\u00f9 piede la diversa via dell\u2019affidamento dell\u2019amministrazione delle carriere del relativo personale a organi collegiali composti da consiglieri togati e laici di derivazione elettiva (quindi non designati per sorteggio), senza che sia esclusa la possibilit\u00e0 che vi sia un unico consiglio (eventualmente diviso in sezioni) per magistrati togati e requirenti (vedi BARTOLE, <em>The internationalisation of constitunional law, <\/em>Oxford \u2013 London \u2013 New York 2020, 82 \u2013 83).<\/p>\n<p>* professore emerito di Diritto costituzionale nell\u2019Universit\u00e0 di Trieste<\/p>\n","protected":false},"excerpt":{"rendered":"<p>di Sergio Bartole* La forma di governo della Repubblica italiana \u00e8 pluralista, non solo in quanto recepisce e proietta a livello di poteri il pluralismo della nostra comunit\u00e0 nazionale, ma anche perch\u00e9 \u00e8 composta di un complesso di istituzioni fra loro separate e destinate a coordinarsi attraverso la collaborazione nonch\u00e9 il bilanciamento delle rispettive attribuzioni &#8230; <a title=\"A proposito del possibile ruolo delle procure a seguito di un\u2019eventuale separazione delle carriere giudiziarie\" class=\"read-more\" href=\"https:\/\/www.lacostituzione.info\/index.php\/2024\/11\/12\/a-proposito-del-possibile-ruolo-delle-procure-a-seguito-di-uneventuale-separazione-delle-carriere-giudiziarie\/\">Leggi tutto<\/a><\/p>\n<div class='heateorSssClear'><\/div><div  class='heateor_sss_sharing_container heateor_sss_horizontal_sharing' data-heateor-sss-href='https:\/\/www.lacostituzione.info\/index.php\/2024\/11\/12\/a-proposito-del-possibile-ruolo-delle-procure-a-seguito-di-uneventuale-separazione-delle-carriere-giudiziarie\/'><div class='heateor_sss_sharing_title' style=\"font-weight:bold\" >Condividi!<\/div><div class=\"heateor_sss_sharing_ul\"><a aria-label=\"Facebook\" class=\"heateor_sss_facebook\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2024%2F11%2F12%2Fa-proposito-del-possibile-ruolo-delle-procure-a-seguito-di-uneventuale-separazione-delle-carriere-giudiziarie%2F\" title=\"Facebook\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#0765FE;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path fill=\"#fff\" d=\"M28 16c0-6.627-5.373-12-12-12S4 9.373 4 16c0 5.628 3.875 10.35 9.101 11.647v-7.98h-2.474V16H13.1v-1.58c0-4.085 1.849-5.978 5.859-5.978.76 0 2.072.15 2.608.298v3.325c-.283-.03-.775-.045-1.386-.045-1.967 0-2.728.745-2.728 2.683V16h3.92l-.673 3.667h-3.247v8.245C23.395 27.195 28 22.135 28 16Z\"><\/path><\/svg><\/span><\/a><a aria-label=\"Twitter\" class=\"heateor_sss_button_twitter\" href=\"https:\/\/twitter.com\/intent\/tweet?text=A%20proposito%20del%20possibile%20ruolo%20delle%20procure%20a%20seguito%20di%20un%E2%80%99eventuale%20separazione%20delle%20carriere%20giudiziarie&url=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2024%2F11%2F12%2Fa-proposito-del-possibile-ruolo-delle-procure-a-seguito-di-uneventuale-separazione-delle-carriere-giudiziarie%2F\" title=\"Twitter\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_twitter\" style=\"background-color:#55acee;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 39 39\"><path d=\"M28 8.557a9.913 9.913 0 0 1-2.828.775 4.93 4.93 0 0 0 2.166-2.725 9.738 9.738 0 0 1-3.13 1.194 4.92 4.92 0 0 0-3.593-1.55 4.924 4.924 0 0 0-4.794 6.049c-4.09-.21-7.72-2.17-10.15-5.15a4.942 4.942 0 0 0-.665 2.477c0 1.71.87 3.214 2.19 4.1a4.968 4.968 0 0 1-2.23-.616v.06c0 2.39 1.7 4.38 3.952 4.83-.414.115-.85.174-1.297.174-.318 0-.626-.03-.928-.086a4.935 4.935 0 0 0 4.6 3.42 9.893 9.893 0 0 1-6.114 2.107c-.398 0-.79-.023-1.175-.068a13.953 13.953 0 0 0 7.55 2.213c9.056 0 14.01-7.507 14.01-14.013 0-.213-.005-.426-.015-.637.96-.695 1.795-1.56 2.455-2.55z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a aria-label=\"Reddit\" class=\"heateor_sss_button_reddit\" href=\"https:\/\/reddit.com\/submit?url=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2024%2F11%2F12%2Fa-proposito-del-possibile-ruolo-delle-procure-a-seguito-di-uneventuale-separazione-delle-carriere-giudiziarie%2F&title=A%20proposito%20del%20possibile%20ruolo%20delle%20procure%20a%20seguito%20di%20un%E2%80%99eventuale%20separazione%20delle%20carriere%20giudiziarie\" title=\"Reddit\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_reddit\" style=\"background-color:#ff5700;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-3.5 -3.5 39 39\"><path d=\"M28.543 15.774a2.953 2.953 0 0 0-2.951-2.949 2.882 2.882 0 0 0-1.9.713 14.075 14.075 0 0 0-6.85-2.044l1.38-4.349 3.768.884a2.452 2.452 0 1 0 .24-1.176l-4.274-1a.6.6 0 0 0-.709.4l-1.659 5.224a14.314 14.314 0 0 0-7.316 2.029 2.908 2.908 0 0 0-1.872-.681 2.942 2.942 0 0 0-1.618 5.4 5.109 5.109 0 0 0-.062.765c0 4.158 5.037 7.541 11.229 7.541s11.22-3.383 11.22-7.541a5.2 5.2 0 0 0-.053-.706 2.963 2.963 0 0 0 1.427-2.51zm-18.008 1.88a1.753 1.753 0 0 1 1.73-1.74 1.73 1.73 0 0 1 1.709 1.74 1.709 1.709 0 0 1-1.709 1.711 1.733 1.733 0 0 1-1.73-1.711zm9.565 4.968a5.573 5.573 0 0 1-4.081 1.272h-.032a5.576 5.576 0 0 1-4.087-1.272.6.6 0 0 1 .844-.854 4.5 4.5 0 0 0 3.238.927h.032a4.5 4.5 0 0 0 3.237-.927.6.6 0 1 1 .844.854zm-.331-3.256a1.726 1.726 0 1 1 1.709-1.712 1.717 1.717 0 0 1-1.712 1.712z\" fill=\"#fff\"\/><\/svg><\/span><\/a><a aria-label=\"Linkedin\" class=\"heateor_sss_button_linkedin\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2024%2F11%2F12%2Fa-proposito-del-possibile-ruolo-delle-procure-a-seguito-di-uneventuale-separazione-delle-carriere-giudiziarie%2F\" title=\"Linkedin\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_linkedin\" style=\"background-color:#0077b5;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path d=\"M6.227 12.61h4.19v13.48h-4.19V12.61zm2.095-6.7a2.43 2.43 0 0 1 0 4.86c-1.344 0-2.428-1.09-2.428-2.43s1.084-2.43 2.428-2.43m4.72 6.7h4.02v1.84h.058c.56-1.058 1.927-2.176 3.965-2.176 4.238 0 5.02 2.792 5.02 6.42v7.395h-4.183v-6.56c0-1.564-.03-3.574-2.178-3.574-2.18 0-2.514 1.7-2.514 3.46v6.668h-4.187V12.61z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a aria-label=\"Pinterest\" class=\"heateor_sss_button_pinterest\" href=\"https:\/\/www.lacostituzione.info\/index.php\/2024\/11\/12\/a-proposito-del-possibile-ruolo-delle-procure-a-seguito-di-uneventuale-separazione-delle-carriere-giudiziarie\/\" onclick=\"event.preventDefault();javascript:void( (function() {var e=document.createElement('script' );e.setAttribute('type','text\/javascript' );e.setAttribute('charset','UTF-8' );e.setAttribute('src','\/\/assets.pinterest.com\/js\/pinmarklet.js?r='+Math.random()*99999999);document.body.appendChild(e)})());\" title=\"Pinterest\" rel=\"noopener\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_pinterest\" style=\"background-color:#cc2329;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-2 -2 35 35\"><path fill=\"#fff\" d=\"M16.539 4.5c-6.277 0-9.442 4.5-9.442 8.253 0 2.272.86 4.293 2.705 5.046.303.125.574.005.662-.33.061-.231.205-.816.27-1.06.088-.331.053-.447-.191-.736-.532-.627-.873-1.439-.873-2.591 0-3.338 2.498-6.327 6.505-6.327 3.548 0 5.497 2.168 5.497 5.062 0 3.81-1.686 7.025-4.188 7.025-1.382 0-2.416-1.142-2.085-2.545.397-1.674 1.166-3.48 1.166-4.689 0-1.081-.581-1.983-1.782-1.983-1.413 0-2.548 1.462-2.548 3.419 0 1.247.421 2.091.421 2.091l-1.699 7.199c-.505 2.137-.076 4.755-.039 5.019.021.158.223.196.314.077.13-.17 1.813-2.247 2.384-4.324.162-.587.929-3.631.929-3.631.46.876 1.801 1.646 3.227 1.646 4.247 0 7.128-3.871 7.128-9.053.003-3.918-3.317-7.568-8.361-7.568z\"\/><\/svg><\/span><\/a><a aria-label=\"Whatsapp\" class=\"heateor_sss_whatsapp\" href=\"https:\/\/api.whatsapp.com\/send?text=A%20proposito%20del%20possibile%20ruolo%20delle%20procure%20a%20seguito%20di%20un%E2%80%99eventuale%20separazione%20delle%20carriere%20giudiziarie%20https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2024%2F11%2F12%2Fa-proposito-del-possibile-ruolo-delle-procure-a-seguito-di-uneventuale-separazione-delle-carriere-giudiziarie%2F\" title=\"Whatsapp\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#55eb4c;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-6 -5 40 40\"><path class=\"heateor_sss_svg_stroke heateor_sss_no_fill\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\" d=\"M 11.579798566743314 24.396926207859085 A 10 10 0 1 0 6.808479557110079 20.73576436351046\"><\/path><path d=\"M 7 19 l -1 6 l 6 -1\" class=\"heateor_sss_no_fill heateor_sss_svg_stroke\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\"><\/path><path d=\"M 10 10 q -1 8 8 11 c 5 -1 0 -6 -1 -3 q -4 -3 -5 -5 c 4 -2 -1 -5 -1 -4\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><\/div><div class=\"heateorSssClear\"><\/div><\/div><div class='heateorSssClear'><\/div>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"enabled":false},"version":2}},"categories":[4],"tags":[608,1848,1849,609],"class_list":["post-9327","post","type-post","status-publish","format-standard","hentry","category-attualita","tag-indipendenza-dei-magistrati","tag-ordinamento-giudiziario","tag-procura-della-repubblica","tag-separazione-delle-carriere"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p84sDq-2qr","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/posts\/9327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/comments?post=9327"}],"version-history":[{"count":0,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/posts\/9327\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/media?parent=9327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/categories?post=9327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/tags?post=9327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}