{"id":9401,"date":"2025-02-26T17:28:02","date_gmt":"2025-02-26T16:28:02","guid":{"rendered":"http:\/\/www.lacostituzione.info\/?p=9401"},"modified":"2025-02-26T20:33:12","modified_gmt":"2025-02-26T19:33:12","slug":"lo-sciopero-dei-magistrati","status":"publish","type":"post","link":"https:\/\/www.lacostituzione.info\/index.php\/2025\/02\/26\/lo-sciopero-dei-magistrati\/","title":{"rendered":"Lo sciopero dei magistrati"},"content":{"rendered":"\n<p>di <strong>Felice Blando<img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9410\" data-permalink=\"https:\/\/www.lacostituzione.info\/index.php\/2025\/02\/26\/lo-sciopero-dei-magistrati\/magistrati-in-sciopero-4\/#main\" data-orig-file=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2025\/02\/magistrati-in-sciopero-3.jpg\" data-orig-size=\"300,168\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"magistrati in sciopero\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2025\/02\/magistrati-in-sciopero-3.jpg\" data-large-file=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2025\/02\/magistrati-in-sciopero-3.jpg\" class=\"size-full wp-image-9410 alignright\" src=\"http:\/\/www.lacostituzione.info\/wp-content\/uploads\/2025\/02\/magistrati-in-sciopero-3.jpg\" alt=\"\" width=\"300\" height=\"168\" \/><\/strong><\/p>\n<p>Da autentico liberale, Giuseppe Maranini combatt\u00e9 per la completa indipendenza della Magistratura, proponendo l\u2019alternativa \u00abmagistrati o funzionari\u00bb. In altre parole, giudici autentici o burocrati nelle mani del potere. Per l\u2019oggi pu\u00f2 anche dirsi che si \u00e8 andati ben oltre. <!--more-->Pi\u00f9 che giudici, i nostri magistrati sono largamente \u00abliberi professionisti\u00bb, e come tale si comportano e si auto-organizzano. Ad esempio, si consentono di riunirsi in congresso per diversi giorni, nel pieno della settimana che dovrebbe essere lavorativa. E molti di loro sono sistematicamente impegnati in dibattiti e consessi di vario tipo. E accade che nel pieno dell\u2019anno giudiziario si proclami uno sciopero contro la proposta di riforma costituzionale di parte del Titolo IV della Costituzione.<\/p>\n<p>Anche qui si vorrebbe sapere come sta la cosa in diritto. Certo il magistrato non pu\u00f2 essere come l\u2019operaio o l\u2019impiegato, con precisi orari di lavoro. Inevitabilmente e largamente \u00e8 lo stesso magistrato a organizzare il suo lavoro. Per quanto concerne, invece, l\u2019esercizio del diritto di sciopero da parte dei magistrati, nulla la Costituzione asserisce in via esplicita: se non fosse cos\u00ec, la soluzione della questione si troverebbe in un\u2019interpretazione logico-sistematica dell\u2019indicazione costituzionale.<\/p>\n<p>In materia, pur essendo da tempo considerato legittimo lo sciopero dei dipendenti pubblici \u2013 beninteso in via generale, cio\u00e8 eccezion fatta per determinate categorie in relazione al tipo di prestazione svolta \u2013 lo sciopero dei magistrati non sembra da considerarsi in tesi legittimo. Se si ritiene che l\u2019esercizio della giurisdizione sia una funzione che renda compartecipi della sovranit\u00e0 (art. 101, 1\u00b0 comma) e che i magistrati concorrano a costituire uno dei poteri dello Stato e abbiano, in aggiunta, il potere di disporre della polizia giudiziaria, ne deriva in via logico-sistematica che essi non possano esercitare il diritto di sciopero: come, a dimostrazione, sarebbe un assurdo logico-giuridico uno sciopero dei membri del Parlamento o dei Ministri.<\/p>\n<p>E non \u00e8 un caso che il modello di Magistratura a cui pensarono i Costituenti fu un modello di \u00abordine autonomo e indipendente da ogni altro potere\u00bb (art. 104, 1\u00b0 comma). Omettendo le infinite discussioni che la formula ha causato, a me pare corretta l\u2019interpretazione che ritiene che la Costituzione abbia pensato alla Magistrature come ad un \u00abpotere\u00bb, in quanto ha dato per presupposto che si tratta di un potere \u00abneutro\u00bb, non avendo essa poteri di indirizzo politico. Questa impostazione mette in luce l\u2019illegittimit\u00e0 dello sciopero della magistratura proclamato per il 27 febbraio di quest\u2019anno per influire su direttive politiche specifiche che proprio a essa si indirizza. In questo caso lo sciopero cesserebbe di operare come uno strumento di autotutela di categoria, per trasformarsi in un indebito tentativo di sovrapposizione dei pubblici funzionari all\u2019organo politico. La Magistratura finisce cos\u00ec col porsi in sostanziale esorbitanza dai limiti della propria competenza costituzionale, mentre, viceversa, il rispetto delle fondamentali scelte politiche legalmente espresse \u00e8 l\u2019abc della democrazia parlamentare.<\/p>\n<p>Di rincalzo, l\u2019ordinamento assicura con altri mezzi l\u2019indipendenza e la libert\u00e0 morale di un organo costituzionalmente neutrale come la Magistratura: sancendo l\u2019inamovibilit\u00e0 del giudice, la sua nomina non elettiva, l\u2019obbligatoriet\u00e0 dell\u2019azione penale, il controllo di costituzionalit\u00e0 delle leggi, l\u2019autogoverno dell\u2019ordine giudiziario. La riforma costituzionale (non della giustizia) ma della gestione delle carriere dei magistrati approvata dalla Camera \u2013 e ora all\u2019esame del Senato: v. A.S. n. 1353 \u2013 pur puntando alla separazione delle carriere fra giudice e pubblico ministero, non prospetta per quest\u2019ultimo il venir meno delle garanzie che gli spettano nell\u2019interesse pubblico. Sergio Bartole \u2013 nel presentare la riforma in questa testata \u2013 ha sottolineato l\u2019affacciarsi di una minacciosa <em>Prokuratura<\/em>, inquadrata in Costituzione. Cos\u00ec il Governo \u2013 di cui non possiamo ignorare il tono vendicativo che attualmente usa verso la Magistratura \u2013 si potrebbe trovare contro inquirenti e giudicanti unitamente. Due corporazioni sono peggio di una!<\/p>\n<p>Resta da fare un\u2019ultima considerazione. Mentre la cultura accademica ufficiale e in particolare la manualistica corrente continua ad accreditare l\u2019immagine del magistrato come arbitro estraneo alle passioni degli uomini comuni e separato dal contesto dei conflitti politici, l\u2019esperienza delle aule giudiziarie e della vita delle istituzioni si affretta a smentire regolarmente la fondatezza delle premesse che sono il sostegno nascosto di quella effigie. La Magistratura non \u00e8 pi\u00f9 un organismo impenetrabile nei confronti delle tensioni e delle pressioni della politica, ma \u00e8 al contrario una cassa di risonanza delle tensioni e delle pressioni medesime.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>di Felice Blando Da autentico liberale, Giuseppe Maranini combatt\u00e9 per la completa indipendenza della Magistratura, proponendo l\u2019alternativa \u00abmagistrati o funzionari\u00bb. In altre parole, giudici autentici o burocrati nelle mani del potere. Per l\u2019oggi pu\u00f2 anche dirsi che si \u00e8 andati ben oltre.<\/p>\n<div class='heateorSssClear'><\/div><div  class='heateor_sss_sharing_container heateor_sss_horizontal_sharing' data-heateor-sss-href='https:\/\/www.lacostituzione.info\/index.php\/2025\/02\/26\/lo-sciopero-dei-magistrati\/'><div class='heateor_sss_sharing_title' style=\"font-weight:bold\" >Condividi!<\/div><div class=\"heateor_sss_sharing_ul\"><a aria-label=\"Facebook\" class=\"heateor_sss_facebook\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2025%2F02%2F26%2Flo-sciopero-dei-magistrati%2F\" title=\"Facebook\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#0765FE;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path fill=\"#fff\" d=\"M28 16c0-6.627-5.373-12-12-12S4 9.373 4 16c0 5.628 3.875 10.35 9.101 11.647v-7.98h-2.474V16H13.1v-1.58c0-4.085 1.849-5.978 5.859-5.978.76 0 2.072.15 2.608.298v3.325c-.283-.03-.775-.045-1.386-.045-1.967 0-2.728.745-2.728 2.683V16h3.92l-.673 3.667h-3.247v8.245C23.395 27.195 28 22.135 28 16Z\"><\/path><\/svg><\/span><\/a><a aria-label=\"Twitter\" class=\"heateor_sss_button_twitter\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Lo%20sciopero%20dei%20magistrati&url=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2025%2F02%2F26%2Flo-sciopero-dei-magistrati%2F\" title=\"Twitter\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_twitter\" style=\"background-color:#55acee;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 39 39\"><path d=\"M28 8.557a9.913 9.913 0 0 1-2.828.775 4.93 4.93 0 0 0 2.166-2.725 9.738 9.738 0 0 1-3.13 1.194 4.92 4.92 0 0 0-3.593-1.55 4.924 4.924 0 0 0-4.794 6.049c-4.09-.21-7.72-2.17-10.15-5.15a4.942 4.942 0 0 0-.665 2.477c0 1.71.87 3.214 2.19 4.1a4.968 4.968 0 0 1-2.23-.616v.06c0 2.39 1.7 4.38 3.952 4.83-.414.115-.85.174-1.297.174-.318 0-.626-.03-.928-.086a4.935 4.935 0 0 0 4.6 3.42 9.893 9.893 0 0 1-6.114 2.107c-.398 0-.79-.023-1.175-.068a13.953 13.953 0 0 0 7.55 2.213c9.056 0 14.01-7.507 14.01-14.013 0-.213-.005-.426-.015-.637.96-.695 1.795-1.56 2.455-2.55z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a aria-label=\"Reddit\" class=\"heateor_sss_button_reddit\" href=\"https:\/\/reddit.com\/submit?url=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2025%2F02%2F26%2Flo-sciopero-dei-magistrati%2F&title=Lo%20sciopero%20dei%20magistrati\" title=\"Reddit\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_reddit\" style=\"background-color:#ff5700;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-3.5 -3.5 39 39\"><path d=\"M28.543 15.774a2.953 2.953 0 0 0-2.951-2.949 2.882 2.882 0 0 0-1.9.713 14.075 14.075 0 0 0-6.85-2.044l1.38-4.349 3.768.884a2.452 2.452 0 1 0 .24-1.176l-4.274-1a.6.6 0 0 0-.709.4l-1.659 5.224a14.314 14.314 0 0 0-7.316 2.029 2.908 2.908 0 0 0-1.872-.681 2.942 2.942 0 0 0-1.618 5.4 5.109 5.109 0 0 0-.062.765c0 4.158 5.037 7.541 11.229 7.541s11.22-3.383 11.22-7.541a5.2 5.2 0 0 0-.053-.706 2.963 2.963 0 0 0 1.427-2.51zm-18.008 1.88a1.753 1.753 0 0 1 1.73-1.74 1.73 1.73 0 0 1 1.709 1.74 1.709 1.709 0 0 1-1.709 1.711 1.733 1.733 0 0 1-1.73-1.711zm9.565 4.968a5.573 5.573 0 0 1-4.081 1.272h-.032a5.576 5.576 0 0 1-4.087-1.272.6.6 0 0 1 .844-.854 4.5 4.5 0 0 0 3.238.927h.032a4.5 4.5 0 0 0 3.237-.927.6.6 0 1 1 .844.854zm-.331-3.256a1.726 1.726 0 1 1 1.709-1.712 1.717 1.717 0 0 1-1.712 1.712z\" fill=\"#fff\"\/><\/svg><\/span><\/a><a aria-label=\"Linkedin\" class=\"heateor_sss_button_linkedin\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2025%2F02%2F26%2Flo-sciopero-dei-magistrati%2F\" title=\"Linkedin\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_linkedin\" style=\"background-color:#0077b5;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path d=\"M6.227 12.61h4.19v13.48h-4.19V12.61zm2.095-6.7a2.43 2.43 0 0 1 0 4.86c-1.344 0-2.428-1.09-2.428-2.43s1.084-2.43 2.428-2.43m4.72 6.7h4.02v1.84h.058c.56-1.058 1.927-2.176 3.965-2.176 4.238 0 5.02 2.792 5.02 6.42v7.395h-4.183v-6.56c0-1.564-.03-3.574-2.178-3.574-2.18 0-2.514 1.7-2.514 3.46v6.668h-4.187V12.61z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a aria-label=\"Pinterest\" class=\"heateor_sss_button_pinterest\" href=\"https:\/\/www.lacostituzione.info\/index.php\/2025\/02\/26\/lo-sciopero-dei-magistrati\/\" onclick=\"event.preventDefault();javascript:void( (function() {var e=document.createElement('script' );e.setAttribute('type','text\/javascript' );e.setAttribute('charset','UTF-8' );e.setAttribute('src','\/\/assets.pinterest.com\/js\/pinmarklet.js?r='+Math.random()*99999999);document.body.appendChild(e)})());\" title=\"Pinterest\" rel=\"noopener\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_pinterest\" style=\"background-color:#cc2329;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-2 -2 35 35\"><path fill=\"#fff\" d=\"M16.539 4.5c-6.277 0-9.442 4.5-9.442 8.253 0 2.272.86 4.293 2.705 5.046.303.125.574.005.662-.33.061-.231.205-.816.27-1.06.088-.331.053-.447-.191-.736-.532-.627-.873-1.439-.873-2.591 0-3.338 2.498-6.327 6.505-6.327 3.548 0 5.497 2.168 5.497 5.062 0 3.81-1.686 7.025-4.188 7.025-1.382 0-2.416-1.142-2.085-2.545.397-1.674 1.166-3.48 1.166-4.689 0-1.081-.581-1.983-1.782-1.983-1.413 0-2.548 1.462-2.548 3.419 0 1.247.421 2.091.421 2.091l-1.699 7.199c-.505 2.137-.076 4.755-.039 5.019.021.158.223.196.314.077.13-.17 1.813-2.247 2.384-4.324.162-.587.929-3.631.929-3.631.46.876 1.801 1.646 3.227 1.646 4.247 0 7.128-3.871 7.128-9.053.003-3.918-3.317-7.568-8.361-7.568z\"\/><\/svg><\/span><\/a><a aria-label=\"Whatsapp\" class=\"heateor_sss_whatsapp\" href=\"https:\/\/api.whatsapp.com\/send?text=Lo%20sciopero%20dei%20magistrati%20https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2025%2F02%2F26%2Flo-sciopero-dei-magistrati%2F\" title=\"Whatsapp\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#55eb4c;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-6 -5 40 40\"><path class=\"heateor_sss_svg_stroke heateor_sss_no_fill\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\" d=\"M 11.579798566743314 24.396926207859085 A 10 10 0 1 0 6.808479557110079 20.73576436351046\"><\/path><path d=\"M 7 19 l -1 6 l 6 -1\" class=\"heateor_sss_no_fill heateor_sss_svg_stroke\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\"><\/path><path d=\"M 10 10 q -1 8 8 11 c 5 -1 0 -6 -1 -3 q -4 -3 -5 -5 c 4 -2 -1 -5 -1 -4\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><\/div><div class=\"heateorSssClear\"><\/div><\/div><div class='heateorSssClear'><\/div>","protected":false},"author":13,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"enabled":false},"version":2}},"categories":[4],"tags":[1860,545,624,609],"class_list":["post-9401","post","type-post","status-publish","format-standard","hentry","category-attualita","tag-magistrati","tag-magistratura","tag-sciopero","tag-separazione-delle-carriere"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p84sDq-2rD","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/posts\/9401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/comments?post=9401"}],"version-history":[{"count":0,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/posts\/9401\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/media?parent=9401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/categories?post=9401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/tags?post=9401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}