{"id":9715,"date":"2025-10-31T15:31:55","date_gmt":"2025-10-31T14:31:55","guid":{"rendered":"https:\/\/www.lacostituzione.info\/?p=9715"},"modified":"2025-10-31T15:32:00","modified_gmt":"2025-10-31T14:32:00","slug":"uno-sguardo-sul-ponte-come-finira","status":"publish","type":"post","link":"https:\/\/www.lacostituzione.info\/index.php\/2025\/10\/31\/uno-sguardo-sul-ponte-come-finira\/","title":{"rendered":"Uno sguardo sul Ponte: come finir\u00e0?"},"content":{"rendered":"\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9716\" data-permalink=\"https:\/\/www.lacostituzione.info\/index.php\/2025\/10\/31\/uno-sguardo-sul-ponte-come-finira\/ponte-2\/#main\" data-orig-file=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2025\/10\/ponte.jpg\" data-orig-size=\"1170,781\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"ponte\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2025\/10\/ponte-300x200.jpg\" data-large-file=\"https:\/\/www.lacostituzione.info\/wp-content\/uploads\/2025\/10\/ponte-1024x684.jpg\" class=\"alignleft size-thumbnail wp-image-9716\" src=\"http:\/\/www.lacostituzione.info\/wp-content\/uploads\/2025\/10\/ponte-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/>di\u00a0<strong><abbr class='c2c-text-hover' title='Professore ordinario di Diritto costituzionale - Universit\u00e0 di Ferrara'>Roberto Bin<\/abbr><\/strong><\/p>\n<p>La violenta reazione dei vertici del Governo alla notizia che la Corte dei conti aveva rifiutato il visto di legittimit\u00e0 al p<span style=\"color: #000000;\">rogetto del ponte deliberato in via definitiva<\/span> sembra ormai sedata. Qualcuno deve aver spiegato alla Presidente e ai Vice-Presidenti del Governo come funzionano le cose.<!--more--> Deve aver spiegato che la Corte dei conti non c&#8217;entra nulla con l&#8217;Ordinamento giudiziario, n\u00e9 con i giudici (la famigerate &#8220;toghe rosse&#8221;) che si oppongono alla riforma costituzionale della c.d. &#8220;separazione della carriere&#8221;; che \u00e8 un organo che esiste da secoli in tutti i regimi liberali (e anche nell&#8217;Unione europea), inventato dai Parlamenti per essere aiutati nella vigilanza sull&#8217;esecuzione delle loro leggi da parte delle autorit\u00e0 di governo; che il suo compito \u00e8 quello, appunto, di giudicare la rispondenza degli atti amministrativi, piccoli o grandi che siano, con le leggi a cui devono dare esecuzione, valutarne cio\u00e8 la legittimit\u00e0; che la Corte dei conti non ha il potere di bloccare il Governo, il quale pu\u00f2 rideliberare l&#8217;atto e riproporlo al controllo; che, in questo caso, la Corte dei conti <em>deve\u00a0<\/em>registrare il provvedimento, riservandosi tuttalpi\u00f9 di segnalare il problema al Parlamento (c.d. &#8220;registrazione con riserva&#8221;). Nessuna bocciatura definitiva, dunque.<\/p>\n<p>Tutto questo deve aver spiegato il bravo consigliere, facendo capire alla Presidente e ai suoi Vice che non era opportuno continuare a indignarsi, ma conviene aspettare che la Corte dei conti, entro 30 giorni, renda pubbliche le sue motivazioni e poi riapprovare la delibera, magari con qualche piccolo adattamento: a questo punto la Corte dovr\u00e0 comunque registrarlo, magari &#8220;con riserva&#8221; con conseguente segnalazione al Parlamento, in cui per\u00f2 il Governo gode di una maggioranza solida e inscalfibile.<\/p>\n<p>Allora \u00e8 fatta, c&#8217;\u00e8 solo da aspettare ancora pochi mesi per mettere la prima pietra, come dichiara Salvini? Forse non \u00e8 cos\u00ec.<\/p>\n<p>La Corte costituzionale, in una lontana <a href=\"https:\/\/giurcost.org\/decisioni\/1976\/0226s-76.html\">sentenza del 1976<\/a>, scritta dalla sua penna pi\u00f9 autorevole (Crisafulli), riconobbe alla Corte dei conti, in sede di controllo preventivo sugli atti del Governo, la qualit\u00e0 di giudice: in quanto tale, pu\u00f2 sollevare la questione di legittimit\u00e0 della legge che autorizza l&#8217;emanzione dell&#8217;atto sottoposto al suo giudizio, se ne sospetta l&#8217;incostituzionalit\u00e0. Fu una sentenza clamorosa, che provoc\u00f2 un&#8217;aspra reazione parlamentare (vedi <a href=\"https:\/\/www.robertobin.it\/ARTICOLI\/Corte%20in%20Parlamento.pdf\">Bin e Bergonzini<\/a>), ma che ha aperto una porta attraverso la quale la Corte dei conti pu\u00f2, in fase di registrazione dell&#8217;atto del Governo (nel nostro caso la <a href=\"https:\/\/www.programmazioneeconomica.gov.it\/media\/3eel5sg1\/esito-cipess-6-agosto-2025.pdf\">delibera<\/a> del Comitato interministeriale per la programmazione economica e lo sviluppo sostenibile &#8211; CIPESS),\u00a0 sollevare la questione di legittimit\u00e0 dell&#8217;atto legislativo che fonda e disciplina l&#8217;intera procedura, ossia del <a href=\"https:\/\/www.normattiva.it\/uri-res\/N2Ls?urn:nir:stato:decreto.legge:2023-03-31;35\">decreto-legge 31 marzo 2023, n. 35<\/a> (<em>Disposizioni urgenti per la realizzazione del collegamento stabile tra la Sicilia e la Calabria<\/em>), come convertito dalla legge 58\/2023 e in seguito pi\u00f9 volte modificato.<\/p>\n<p>Quali possano essere i vizi di legittimit\u00e0 costituzionale della disciplina legislativa su cui la costruzione del Ponte si regge non sono in grado di ipotizzarlo. Ma c&#8217;\u00e8 un altra questione di cui va tenuto il conto: riguarda la compatibilit\u00e0 della delibera CIPESS (e della sua stessa base legislativa, forse) con l&#8217;ordinamento europeo: vi sono profili ambientali, gi\u00e0 denunciati alla Commissione UE dalle associazioni ambientalistiche; e poi vi \u00e8, soprattutto, la questione dell&#8217;affidamento dei lavori a WeBuild senza una nuova gara, che sarebbe stata necessaria visto il raddoppio dei costi rispetto alla gara effettuata nel 2005; se cos\u00ec, sarebbe in violazione della normativa europea sugli appalti.<\/p>\n<p>Naturalmente le violazione delle norme europee potrebbe essere contestata dalla Commissione direttamente attraverso la procedura d&#8217;infrazione: ma questa non avrebbe l&#8217;effetto che si potrebbe produrre se fosse la Corte dei conti, in sede di controllo di legittimit\u00e0, a denunciare la infrazione del diritto UE, attraverso un rinvio pregiudiziale alla Corte di giustizia di Lussemburgo. Sia in questa ipotesi, che nell&#8217;ipotesi di una questione di legittimit\u00e0 della legge che introduce la procedura, l&#8217;effetto sarebbe lo stesso:\u00a0 che la Corte dovrebbe sospendere la registrazione della delibera CIPESS per tutto il tempo necessario alla decisione del giudice a cui la Corte dei conti si \u00e8 rivolta. Solo in questo modo la Corte giocherebbe d&#8217;anticipo, impedendo la posa della &#8220;prima pietra&#8221; e il rischio che essa resti l&#8217;ennesimo scempio dell&#8217;ambiente naturale a causa di un&#8217;opera incompiuta.<\/p>\n\n\n\n\n","protected":false},"excerpt":{"rendered":"<p>di\u00a0<abbr class='c2c-text-hover' title='Professore ordinario di Diritto costituzionale - Universit\u00e0 di Ferrara'>Roberto Bin<\/abbr> La violenta reazione dei vertici del Governo alla notizia che la Corte dei conti aveva rifiutato il visto di legittimit\u00e0 al progetto del ponte deliberato in via definitiva sembra ormai sedata. Qualcuno deve aver spiegato alla Presidente e ai Vice-Presidenti del Governo come funzionano le cose.<\/p>\n<div class='heateorSssClear'><\/div><div  class='heateor_sss_sharing_container heateor_sss_horizontal_sharing' data-heateor-sss-href='https:\/\/www.lacostituzione.info\/index.php\/2025\/10\/31\/uno-sguardo-sul-ponte-come-finira\/'><div class='heateor_sss_sharing_title' style=\"font-weight:bold\" >Condividi!<\/div><div class=\"heateor_sss_sharing_ul\"><a aria-label=\"Facebook\" class=\"heateor_sss_facebook\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2025%2F10%2F31%2Funo-sguardo-sul-ponte-come-finira%2F\" title=\"Facebook\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#0765FE;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path fill=\"#fff\" d=\"M28 16c0-6.627-5.373-12-12-12S4 9.373 4 16c0 5.628 3.875 10.35 9.101 11.647v-7.98h-2.474V16H13.1v-1.58c0-4.085 1.849-5.978 5.859-5.978.76 0 2.072.15 2.608.298v3.325c-.283-.03-.775-.045-1.386-.045-1.967 0-2.728.745-2.728 2.683V16h3.92l-.673 3.667h-3.247v8.245C23.395 27.195 28 22.135 28 16Z\"><\/path><\/svg><\/span><\/a><a aria-label=\"Twitter\" class=\"heateor_sss_button_twitter\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Uno%20sguardo%20sul%20Ponte%3A%20come%20finir%C3%A0%3F&url=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2025%2F10%2F31%2Funo-sguardo-sul-ponte-come-finira%2F\" title=\"Twitter\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_twitter\" style=\"background-color:#55acee;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 39 39\"><path d=\"M28 8.557a9.913 9.913 0 0 1-2.828.775 4.93 4.93 0 0 0 2.166-2.725 9.738 9.738 0 0 1-3.13 1.194 4.92 4.92 0 0 0-3.593-1.55 4.924 4.924 0 0 0-4.794 6.049c-4.09-.21-7.72-2.17-10.15-5.15a4.942 4.942 0 0 0-.665 2.477c0 1.71.87 3.214 2.19 4.1a4.968 4.968 0 0 1-2.23-.616v.06c0 2.39 1.7 4.38 3.952 4.83-.414.115-.85.174-1.297.174-.318 0-.626-.03-.928-.086a4.935 4.935 0 0 0 4.6 3.42 9.893 9.893 0 0 1-6.114 2.107c-.398 0-.79-.023-1.175-.068a13.953 13.953 0 0 0 7.55 2.213c9.056 0 14.01-7.507 14.01-14.013 0-.213-.005-.426-.015-.637.96-.695 1.795-1.56 2.455-2.55z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a aria-label=\"Reddit\" class=\"heateor_sss_button_reddit\" href=\"https:\/\/reddit.com\/submit?url=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2025%2F10%2F31%2Funo-sguardo-sul-ponte-come-finira%2F&title=Uno%20sguardo%20sul%20Ponte%3A%20come%20finir%C3%A0%3F\" title=\"Reddit\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_reddit\" style=\"background-color:#ff5700;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-3.5 -3.5 39 39\"><path d=\"M28.543 15.774a2.953 2.953 0 0 0-2.951-2.949 2.882 2.882 0 0 0-1.9.713 14.075 14.075 0 0 0-6.85-2.044l1.38-4.349 3.768.884a2.452 2.452 0 1 0 .24-1.176l-4.274-1a.6.6 0 0 0-.709.4l-1.659 5.224a14.314 14.314 0 0 0-7.316 2.029 2.908 2.908 0 0 0-1.872-.681 2.942 2.942 0 0 0-1.618 5.4 5.109 5.109 0 0 0-.062.765c0 4.158 5.037 7.541 11.229 7.541s11.22-3.383 11.22-7.541a5.2 5.2 0 0 0-.053-.706 2.963 2.963 0 0 0 1.427-2.51zm-18.008 1.88a1.753 1.753 0 0 1 1.73-1.74 1.73 1.73 0 0 1 1.709 1.74 1.709 1.709 0 0 1-1.709 1.711 1.733 1.733 0 0 1-1.73-1.711zm9.565 4.968a5.573 5.573 0 0 1-4.081 1.272h-.032a5.576 5.576 0 0 1-4.087-1.272.6.6 0 0 1 .844-.854 4.5 4.5 0 0 0 3.238.927h.032a4.5 4.5 0 0 0 3.237-.927.6.6 0 1 1 .844.854zm-.331-3.256a1.726 1.726 0 1 1 1.709-1.712 1.717 1.717 0 0 1-1.712 1.712z\" fill=\"#fff\"\/><\/svg><\/span><\/a><a aria-label=\"Linkedin\" class=\"heateor_sss_button_linkedin\" href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2025%2F10%2F31%2Funo-sguardo-sul-ponte-come-finira%2F\" title=\"Linkedin\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_linkedin\" style=\"background-color:#0077b5;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"0 0 32 32\"><path d=\"M6.227 12.61h4.19v13.48h-4.19V12.61zm2.095-6.7a2.43 2.43 0 0 1 0 4.86c-1.344 0-2.428-1.09-2.428-2.43s1.084-2.43 2.428-2.43m4.72 6.7h4.02v1.84h.058c.56-1.058 1.927-2.176 3.965-2.176 4.238 0 5.02 2.792 5.02 6.42v7.395h-4.183v-6.56c0-1.564-.03-3.574-2.178-3.574-2.18 0-2.514 1.7-2.514 3.46v6.668h-4.187V12.61z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a aria-label=\"Pinterest\" class=\"heateor_sss_button_pinterest\" href=\"https:\/\/www.lacostituzione.info\/index.php\/2025\/10\/31\/uno-sguardo-sul-ponte-come-finira\/\" onclick=\"event.preventDefault();javascript:void( (function() {var e=document.createElement('script' );e.setAttribute('type','text\/javascript' );e.setAttribute('charset','UTF-8' );e.setAttribute('src','\/\/assets.pinterest.com\/js\/pinmarklet.js?r='+Math.random()*99999999);document.body.appendChild(e)})());\" title=\"Pinterest\" rel=\"noopener\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg heateor_sss_s__default heateor_sss_s_pinterest\" style=\"background-color:#cc2329;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-2 -2 35 35\"><path fill=\"#fff\" d=\"M16.539 4.5c-6.277 0-9.442 4.5-9.442 8.253 0 2.272.86 4.293 2.705 5.046.303.125.574.005.662-.33.061-.231.205-.816.27-1.06.088-.331.053-.447-.191-.736-.532-.627-.873-1.439-.873-2.591 0-3.338 2.498-6.327 6.505-6.327 3.548 0 5.497 2.168 5.497 5.062 0 3.81-1.686 7.025-4.188 7.025-1.382 0-2.416-1.142-2.085-2.545.397-1.674 1.166-3.48 1.166-4.689 0-1.081-.581-1.983-1.782-1.983-1.413 0-2.548 1.462-2.548 3.419 0 1.247.421 2.091.421 2.091l-1.699 7.199c-.505 2.137-.076 4.755-.039 5.019.021.158.223.196.314.077.13-.17 1.813-2.247 2.384-4.324.162-.587.929-3.631.929-3.631.46.876 1.801 1.646 3.227 1.646 4.247 0 7.128-3.871 7.128-9.053.003-3.918-3.317-7.568-8.361-7.568z\"\/><\/svg><\/span><\/a><a aria-label=\"Whatsapp\" class=\"heateor_sss_whatsapp\" href=\"https:\/\/api.whatsapp.com\/send?text=Uno%20sguardo%20sul%20Ponte%3A%20come%20finir%C3%A0%3F%20https%3A%2F%2Fwww.lacostituzione.info%2Findex.php%2F2025%2F10%2F31%2Funo-sguardo-sul-ponte-come-finira%2F\" title=\"Whatsapp\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:32px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"heateor_sss_svg\" style=\"background-color:#55eb4c;width:35px;height:35px;display:inline-block;opacity:1;float:left;font-size:32px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-6 -5 40 40\"><path class=\"heateor_sss_svg_stroke heateor_sss_no_fill\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\" d=\"M 11.579798566743314 24.396926207859085 A 10 10 0 1 0 6.808479557110079 20.73576436351046\"><\/path><path d=\"M 7 19 l -1 6 l 6 -1\" class=\"heateor_sss_no_fill heateor_sss_svg_stroke\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\"><\/path><path d=\"M 10 10 q -1 8 8 11 c 5 -1 0 -6 -1 -3 q -4 -3 -5 -5 c 4 -2 -1 -5 -1 -4\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><\/div><div class=\"heateorSssClear\"><\/div><\/div><div class='heateorSssClear'><\/div>","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"enabled":false},"version":2}},"categories":[4],"tags":[300,1908,1907],"class_list":["post-9715","post","type-post","status-publish","format-standard","hentry","category-attualita","tag-corte-dei-conti","tag-giudizio-di-legittimita","tag-ponte-sullo-stretto"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p84sDq-2wH","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/posts\/9715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/comments?post=9715"}],"version-history":[{"count":0,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/posts\/9715\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/media?parent=9715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/categories?post=9715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lacostituzione.info\/index.php\/wp-json\/wp\/v2\/tags?post=9715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}